{"id":2299,"date":"2007-10-02T09:58:31","date_gmt":"2007-10-02T08:58:31","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/webbung\/"},"modified":"2023-12-18T08:48:36","modified_gmt":"2023-12-18T07:48:36","slug":"webbung","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/","title":{"rendered":"Webbung"},"content":{"rendered":"<p>Mein Nachbar, der <a href=\"http:\/\/www.pernsteiner.net\" title=\"Pernsteiner\" target=\"_blank\" rel=\"noopener\">Konditormeister Johannes Pernsteiner<\/a>, hat heute Geburtstag. Da m\u00f6chte ich nicht vers\u00e4umen, ihm an dieser Stelle meine herzlichen Gl\u00fcckw\u00fcnsche zu \u00fcbermitteln. <fn>Nat\u00fcrlich k\u00f6nnte ich auch einfach die vier Stockwerke heruntergehen und ihm pers\u00f6nlich das Beste w\u00fcnschen. Aber dann w\u00fcrde der gute Mann mich nur wieder in ein Gespr\u00e4ch verwickeln, mir etwas zu essen und trinken anbieten und sich erinnern, wie ich wohl aussehe.<\/fn> Der gute Mann war in diesem Jahr nicht faul und hat einen <a href=\"http:\/\/www.pernsteiner.biz\" title=\"Shop vom Perni\" target=\"_blank\" rel=\"noopener\">Internet-Shop<\/a> eingerichtet, in welchem man manche seine K\u00f6stlichkeiten erwerben kann. Da sich die Sachen beinahe \u00fcberschlagen, hat er gerade zwei neue Produkte kredenzt: Eine <a href=\"https:\/\/shop.strato.de\/epages\/61312534.sf\/secYhmnp7dZ4bs\/?ObjectPath=\/Shops\/61312534\/Products\/trueffel-erdbeere\" title=\"Erdbeer\" target=\"_blank\" rel=\"noopener\">Erdbeer-Tr\u00fcffel mit wildem Urwaldpfeffer<\/a> und eine <a href=\"http:\/\/shop.strato.de\/epages\/61312534.sf\/secYhmnp7dZ4bs\/?ObjectPath=\/Shops\/61312534\/Products\/trueffel-grappa\">Grappa del Veneto mit Traube<\/a> genannte Tr\u00fcffel-Schokolade.  <\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg?w=1200\" alt=\"Perni schaut gut\" align=\"bottom\" \/><\/p>\n<p>Damit nicht genug, seit kurzem schm\u00fccken sich diese Tr\u00fcffel-Schokoladen mit dem Bio-Siegel. Und zu allem \u00dcberfluss sind diese Tr\u00fcffel-Schokoladen nominiert f\u00fcr den Living-At-Home-Award, der am kommenden Donnerstag in K\u00f6ln verliehen wird. Da w\u00fcnsche ich ihm auch einen prima Erfolg.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein Nachbar, der Konditormeister Johannes Pernsteiner, hat heute Geburtstag. Da m\u00f6chte ich nicht vers\u00e4umen, ihm an dieser Stelle meine herzlichen Gl\u00fcckw\u00fcnsche zu \u00fcbermitteln. Nat\u00fcrlich k\u00f6nnte ich auch einfach die vier Stockwerke heruntergehen und ihm pers\u00f6nlich das Beste w\u00fcnschen. Aber dann w\u00fcrde der gute Mann mich nur wieder in ein Gespr\u00e4ch verwickeln, mir etwas zu essen [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":1060,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-2299","post","type-post","status-publish","format-standard","hentry","entry"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webbung - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webbung - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Mein Nachbar, der Konditormeister Johannes Pernsteiner, hat heute Geburtstag. Da m\u00f6chte ich nicht vers\u00e4umen, ihm an dieser Stelle meine herzlichen Gl\u00fcckw\u00fcnsche zu \u00fcbermitteln. Nat\u00fcrlich k\u00f6nnte ich auch einfach die vier Stockwerke heruntergehen und ihm pers\u00f6nlich das Beste w\u00fcnschen. Aber dann w\u00fcrde der gute Mann mich nur wieder in ein Gespr\u00e4ch verwickeln, mir etwas zu essen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2007-10-02T08:58:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T07:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg\" \/>\n<meta name=\"author\" content=\"hufi\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"hufi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/\"},\"author\":{\"name\":\"hufi\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/8da17b924efd188d2d5ede4e82be2f5d\"},\"headline\":\"Webbung\",\"datePublished\":\"2007-10-02T08:58:31+00:00\",\"dateModified\":\"2023-12-18T07:48:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.urteilskraft.de\\\/kritik\\\/wp-content\\\/uploads\\\/2007\\\/10\\\/perni-3151.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/\",\"name\":\"Webbung - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.urteilskraft.de\\\/kritik\\\/wp-content\\\/uploads\\\/2007\\\/10\\\/perni-3151.jpg\",\"datePublished\":\"2007-10-02T08:58:31+00:00\",\"dateModified\":\"2023-12-18T07:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.urteilskraft.de\\\/kritik\\\/wp-content\\\/uploads\\\/2007\\\/10\\\/perni-3151.jpg\",\"contentUrl\":\"http:\\\/\\\/www.urteilskraft.de\\\/kritik\\\/wp-content\\\/uploads\\\/2007\\\/10\\\/perni-3151.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2007\\\/10\\\/webbung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0085\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2005\\\/11\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webbung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/8da17b924efd188d2d5ede4e82be2f5d\",\"name\":\"hufi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&d=blank&r=g\",\"caption\":\"hufi\"},\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/hufi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webbung - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/","og_locale":"de_DE","og_type":"article","og_title":"Webbung - Kritische Masse","og_description":"Mein Nachbar, der Konditormeister Johannes Pernsteiner, hat heute Geburtstag. Da m\u00f6chte ich nicht vers\u00e4umen, ihm an dieser Stelle meine herzlichen Gl\u00fcckw\u00fcnsche zu \u00fcbermitteln. Nat\u00fcrlich k\u00f6nnte ich auch einfach die vier Stockwerke heruntergehen und ihm pers\u00f6nlich das Beste w\u00fcnschen. Aber dann w\u00fcrde der gute Mann mich nur wieder in ein Gespr\u00e4ch verwickeln, mir etwas zu essen [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2007-10-02T08:58:31+00:00","article_modified_time":"2023-12-18T07:48:36+00:00","og_image":[{"url":"http:\/\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg","type":"","width":"","height":""}],"author":"hufi","twitter_misc":{"Verfasst von":"hufi","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/"},"author":{"name":"hufi","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/8da17b924efd188d2d5ede4e82be2f5d"},"headline":"Webbung","datePublished":"2007-10-02T08:58:31+00:00","dateModified":"2023-12-18T07:48:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/"},"wordCount":173,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#primaryimage"},"thumbnailUrl":"http:\/\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/","name":"Webbung - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#primaryimage"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#primaryimage"},"thumbnailUrl":"http:\/\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg","datePublished":"2007-10-02T08:58:31+00:00","dateModified":"2023-12-18T07:48:36+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#primaryimage","url":"http:\/\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg","contentUrl":"http:\/\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/10\/perni-3151.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/10\/webbung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"\u0085","item":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/11\/content\/"},{"@type":"ListItem","position":3,"name":"Webbung"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/8da17b924efd188d2d5ede4e82be2f5d","name":"hufi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&d=blank&r=g","caption":"hufi"},"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/hufi\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":[],"post_class":[["post-2299","post","type-post","status-publish","format-standard","hentry","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/4acd29497e831db3bb6cf332b3f72f6425714e08ad21fafe27722485bc7bceab?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":1683,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/04\/geschlechtstotale\/","url_meta":{"origin":2299,"position":0},"title":"Geschlechtstotale","author":"huflaikhan","date":"6. April 2006","format":false,"excerpt":"Gestern abend gab es taktlos im Rundfunk. Es fing damit schlecht an, dass ich vergessen hatte meinen Akku in die Kamera zu pflazen. Ohne Strom l\u00e4uft das eben nicht. Im Boder versunken w\u00e4re ich da am liebsten. Die Sendung selbst mit dem schwierigen Thema \u201eZu nah - Panische Gef\u00fchle im\u2026","rel":"","context":"Mit 10 Kommentaren","block_context":{"text":"Mit 10 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/04\/geschlechtstotale\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2365,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2008\/01\/der-unterschied-zwischen-telemann-und-den-teletubbies\/","url_meta":{"origin":2299,"position":1},"title":"Der Unterschied zwischen Telemann und den Teletubbies?","author":"hufi","date":"18. Januar 2008","format":false,"excerpt":"Auf einen einfachen Hinweis hin sei hier ein Appell zur Abschaffung des Musikabiturs in der jetzigen Form formuliert. So wie es in der Sendung taktlos am 13. Januar passiert ist. [display_podcast] Ich habe es leider nicht selbst einsprechen k\u00f6nnen, da im Urlaub noch gewesen. W\u00fcnsche ein sch\u00f6nes Wochenende allerseits.","rel":"","context":"Mit 6 Kommentaren","block_context":{"text":"Mit 6 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2008\/01\/der-unterschied-zwischen-telemann-und-den-teletubbies\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2269,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/08\/heilbad-germania\/","url_meta":{"origin":2299,"position":2},"title":"Heilbad Germania","author":"hufi","date":"23. August 2007","format":false,"excerpt":"ICEs demn\u00e4chst wohl nur noch mit Raucherabteilen. (!!) Zumindest kann man bei Ticketbestellungen sich nicht mehr aussuchen, ob man in einem Nichtraucherbereich fahren will. Ich finde das \u00e4u\u00dferst r\u00fccksichtslos von den Rauchern, aber wirklich jetzt. Die hatten immer schon eine fantastische Lobbyarbeit gemacht, diese stinkenden Gesundheitsm\u00f6rder. Der Marlboro-Mann scheint gesiegt\u2026","rel":"","context":"In \"Deutschland\"","block_context":{"text":"Deutschland","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/deutschland\/"},"img":{"alt_text":"herbst77","src":"https:\/\/i0.wp.com\/www.urteilskraft.de\/kritik\/wp-content\/uploads\/2007\/08\/herbst77.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1913,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/10\/um-240-grad-gedreht\/","url_meta":{"origin":2299,"position":3},"title":"Um 240 Grad gedreht \u0085","author":"huflaikhan","date":"19. Oktober 2006","format":false,"excerpt":"!~~1\/reichstag-bruecke-kompletto.jpg|Da sieht man mal, wie man dem Motiv folgt und damit ins Wasser steigt. Da kannste dir drehen und wenden. Besser w\u00e4r ein Stativ wohl.~~!\u0085 und doch nicht geklappt. Da sieht man mal, wie man dem Motiv folgt und damit ins Wasser steigt. Da kannste dir drehen und wenden. Besser\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8744,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2018\/01\/das-denken-ueberwinden-eine-anleitung-von-marco-buschmann-fdp\/","url_meta":{"origin":2299,"position":4},"title":"Das Denken \u00fcberwinden! Eine Anleitung von Marco Buschmann (FDP)","author":"der huflaikhan","date":"14. Januar 2018","format":false,"excerpt":"Ach, wenn doch die Kritiker der sogenannten \"68er\" nur nicht so hinterh\u00e4ltig w\u00e4ren. Da gab es gestern einen Text in der WELT, in der der parlamentarische\u00a0 Gesch\u00e4ftsf\u00fchrer der FDP-Fraktion im Bundestag, Marco Buschmann, als Autor herbeigeholt wird und einen \"Essay\" abliefert mit der \u00dcberschrift: \"Das Denken der 68er endlich \u00fcberwinden.\"\u2026","rel":"","context":"In &quot;die Kommunikation&quot;","block_context":{"text":"die Kommunikation","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/die-kommunikation\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10488,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2024\/12\/bleibeverhandlungen-jetzt\/","url_meta":{"origin":2299,"position":5},"title":"Bleibeverhandlungen, jetzt!","author":"der huflaikhan","date":"11. Dezember 2024","format":false,"excerpt":"Ich finde es absolut gut f\u00fcr unsere gesellschaftliche Vielfalt und Herzlichkeit, wenn diese Familie bliebe. Man muss nicht Abschiebe-, sondern Bleibeverhandlungen f\u00fchren.","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Wasser wartet. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2023\/12\/wasser3-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2023\/12\/wasser3-scaled.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2023\/12\/wasser3-scaled.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2023\/12\/wasser3-scaled.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2023\/12\/wasser3-scaled.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/2299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=2299"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/2299\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=2299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=2299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=2299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}