{"id":2620,"date":"2009-09-15T09:44:18","date_gmt":"2009-09-15T08:44:18","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/vielfalt-durch-geschwaetzigkeit\/"},"modified":"2023-12-18T08:48:13","modified_gmt":"2023-12-18T07:48:13","slug":"vielfalt-durch-geschwaetzigkeit","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/","title":{"rendered":"Manifeste Geschw\u00e4tzigkeitsleere"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Manifeste%20Geschw%C3%A4tzigkeitsleere https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Manifeste%20Geschw%C3%A4tzigkeitsleere https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Manifeste%20Geschw%C3%A4tzigkeitsleere%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div><blockquote>\n<p>Seit je hat Aufkl\u00e4rung im umfassendsten Sinn fortschreitenden Denkens das Ziel verfolgt, von den Menschen die Furcht zu nehmen und sie als Herren einzusetzen. Aber die vollends aufgekl\u00e4rte Erde strahlt im Zeichen triumphalen Unheils.<sup class=\"modern-footnotes-footnote \" data-mfn=\"1\" data-mfn-post-scope=\"0000000000003e910000000000000000_2620\"><a href=\"javascript:void(0)\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-0000000000003e910000000000000000_2620-1\">1<\/a><\/sup><span id=\"mfn-content-0000000000003e910000000000000000_2620-1\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"1\">[Band 3: Dialektik der Aufkl\u00e4rung: Begriff der Aufkl\u00e4rung. Theodor W. Adorno: Gesammelte Schriften, S. 1105 (vgl. GS 3, S. 19) http:\/\/www.digitale-bibliothek.de\/band97.htm ]<\/span><\/p>\n<p><!--more--><\/p>\n<blockquote>\n<p>Seit je hat Aufkl\u00e4rung im umfassendsten Sinn fortschreitenden Denkens das Ziel verfolgt, von den Menschen die Furcht zu nehmen und sie als Herren einzusetzen. Aber die vollends aufgekl\u00e4rte Erde strahlt im Zeichen triumphalen Unheils.<sup class=\"modern-footnotes-footnote \" data-mfn=\"2\" data-mfn-post-scope=\"0000000000003e910000000000000000_2620\"><a href=\"javascript:void(0)\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-0000000000003e910000000000000000_2620-2\">2<\/a><\/sup><span id=\"mfn-content-0000000000003e910000000000000000_2620-2\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"2\">[Band 3: Dialektik der Aufkl\u00e4rung: Begriff der Aufkl\u00e4rung. Theodor W. Adorno: Gesammelte Schriften, S. 1105 (vgl. GS 3, S. 19) http:\/\/www.digitale-bibliothek.de\/band97.htm ]<\/span><\/p>\n<\/blockquote>\n<p>Und so \u00e4hnlich ist es mit dem Wissen. Das verbreite sich jetzt n\u00e4mlich ungehemmt und in vielen T\u00f6nen und T\u00f6nungen. Es wird geschrieben wie vielleicht niemals zuvor in der Geschichte, in jedem Fall wird es jedoch in st\u00e4rkerem Ma\u00dfe ver\u00f6ffentlicht. Informationen prasseln von allen Seiten ein. Von Agenturen, von Privatpersonen, in B\u00fcchern, Zeitungen, Zeitschriften, Fensehprogrammen, Blogs, Twitterfeeds und in &#8220;sozialen Netzwerken&#8221; &#8211; all\u00fcberall.<\/p>\n<p>Der Output ist riesig. Aber wo man auch hinschaut, insbesondere bei den Apologeten dieser Entwicklungen, insgeheim scheint man anzunehmen, dass damit auch die Qualit\u00e4t der Information besser w\u00fcrde.   Das scheint aber nicht der Fall zu sein, das m\u00fcssen selbst die lauteren Denker der Web eingestehen.<\/p>\n<p>In ihren <a href=\"http:\/\/www.internet-manifest.de\/\">Manifesten<\/a> und Losungen, in ihren Zukunftsszenarien und wenigen Utopien. Das Soziale der Entwicklung bleibt in fast allen F\u00e4llen eine Leerstelle in der Argumentation.  Im gegenw\u00e4rtig im Umlauf befindlichen Internet-Manifest liest man beispielsweise unter Punkt 5: <strong>Das Internet ist der Sieg der Information.<\/strong><\/p>\n<blockquote>\n<p>Bisher ordneten, erzwungen durch die unzul\u00e4ngliche Technologie, Institutionen wie Medienh\u00e4user, Forschungsstellen oder \u00f6ffentliche Einrichtungen die Informationen der Welt. Nun richtet sich jeder B\u00fcrger seine individuellen Nachrichtenfilter ein, w\u00e4hrend Suchmaschinen Informationsmengen in nie gekanntem Umfang erschlie\u00dfen. Der einzelne Mensch kann sich so gut informieren wie nie zuvor.<\/p>\n<\/blockquote>\n<p>Was hat es zum Beispiel mit der unzul\u00e4nglichen Technologie auf sich. Ist hier unzul\u00e4nglich als unzug\u00e4nglich gemeint? Da nun Suchmaschinen das komplizierte Aufsuchen von Inhalten erh\u00f6hen k\u00f6nnen. Sofern a) Suchmaschinen darauf \u00fcberhaupt zugreifen k\u00f6nnen? Ist es nicht vielmehr so, dass auch gegenw\u00e4rtig nur das gefunden werden kann, was f\u00fcr diese neuen Instrumente \u00fcberhaupt lesbar ist? Existente Informationen, die nicht von Suchmaschinen entdeckt werden, werden auch zuk\u00fcnftig dann dieser Generation von Informationssammlern fremd bleiben. Neue Informationen, das mag stimmen, erg\u00e4nzen sich zu einem Vielerlei in &#8220;nicht gekanntem Umfang&#8221;.<\/p>\n<p>Das Vertrauen in diese Technik ist &#8220;die&#8221; Grundlage dieses Denkens. Weshalb die Informationen deshalb besser sein sollen, kann&nbsp; aber auch niemand erkl\u00e4ren. Im Gegenteil scheint es auch in dieser neuen Welt problamatisch zu sein, die richtigen Informationen herauszupicken. Fehlinformationen verbreiten sich auf diese Weise ja nicht weniger &#8211; sondern, wenn der Blick nicht t\u00e4uscht, hervorragend.&nbsp;<\/p>\n<p>Der Strudel der Dummheiten wird nicht weniger, blo\u00df weil es diese Technologieentwicklung gibt. Wer versteht denn, wie Suchmaschinen richtig finden. Und wer bedient diese Maschinen?<\/p>\n<p>Information ist kein Allheilmittel. Im Gegenteil sind nicht zwingend st\u00e4rker informierte Menschen besser informierte Menschen. Es geht um die mechanisch gestrickte Platzierung von Informationen durch bestimmte weitere Techniken. Search Engine Optimization (Optimierung f\u00fcr Suchmaschinen) geh\u00f6rt zu Handwerk, ein an bestimmten Orten plazierter Inhalt ist nolens volens besser zu aufzufinden, als einer an einem selten besuchten Platz. Die G\u00fcte, Wahrhafttigkeit oder Richtigkeit der Information ber\u00fchrt das aber herzlich wenig.&nbsp;<\/p>\n<p>Man kennt die Blogs, die nicht so reich an Reichweite sind, deren Gehalt dennoch \u00fcber vielem anderen steht oder die sogar explizit Suchmaschinen von ihrer Indizierung ausschlie\u00dfen, damit sie nicht im Get\u00fcmmel der Hype-Infos als blo\u00dfe andere Schattierung auftauchen. &#8220;Wer nicht will, der hat schon,&#8221; k\u00f6nnte man meinen. Genauso gut k\u00f6nnte sich der Buchautor wehren, in eine \u00f6ffentliche Bibliothek aufgenommen zu werden. Das eine gilt aber nicht umgekehrt f\u00fcr das andere. Alle, die die Besonderheiten des Netzes preisen, sollten das l\u00e4ngst wissen.<\/p>\n<p>Suchmaschinen wird einer Objektivit\u00e4t zugetraut, die sie nicht haben. Das w\u00fcrde vielleicht niemand in dieser Weise so zugeben, wenn aber dagegen die Auswahl durch Menschen gleichzeitig als fehlerhaft zugestanden wird, als Akt der Manipulation vielleicht sogar oder der Zensur, so gibt man der Maschine indirekt eben doch recht. Denn die Alternative entz\u00fcckt nicht.<\/p>\n<p>Und so eilen sie denn von Meeting zu Meeting, von Lichthof zu Lichthof. Und ein neuer Berufsstand feiert das am meisten, der sich aber hinter unklaren Worten und Gesten versteckt: den Managern von Informationen. Auch Kultur ist eine solche Information, die sich nun im Managementwesen anbiedern muss. An Menschen, die nun auf die \u00dcbersetzung f\u00fcr das maschinelle Auslesen der Inhalte spezialisiert haben. Das gilt f\u00fcr die alte Welt ebenso wie wie f\u00fcr die neue. Nur fragt sich, wo die Priorit\u00e4t dieses Tuns liegt: bei der Anpassungsarbeit oder bei der Recherche &#8220;guter&#8221; Inhalte?<\/p>\n<p>Unvergleichlich sch\u00f6ner formuliert:<\/p>\n<blockquote>\n<p><em>Technik ist das Wesen dieses Wissens<\/em>. Es zielt nicht auf Begriffe und Bilder, nicht auf das Gl\u00fcck der Einsicht, sondern auf Methode, Ausnutzung der Arbeit anderer, Kapital. Die vielen Dinge, die es nach Bacon noch aufbewahrt, sind selbst wieder nur Instrumente: das Radio als sublimierte Druckerpresse, das Sturzkampfflugzeug als wirksamere Artillerie, die Fernsteuerung als der verl\u00e4\u00dflichere Kompa\u00df. Was die Menschen von der Natur lernen wollen, ist, sie anzuwenden, um sie und die Menschen vollends zu beherrschen. Nichts anderes gilt. R\u00fccksichtslos gegen sich selbst hat die Aufkl\u00e4rung noch den letzten Rest ihres eigenen Selbstbewu\u00dftseins ausgebrannt.<sup class=\"modern-footnotes-footnote \" data-mfn=\"3\" data-mfn-post-scope=\"0000000000003e910000000000000000_2620\"><a href=\"javascript:void(0)\"  role=\"button\" aria-pressed=\"false\" aria-describedby=\"mfn-content-0000000000003e910000000000000000_2620-3\">3<\/a><\/sup><span id=\"mfn-content-0000000000003e910000000000000000_2620-3\" role=\"tooltip\" class=\"modern-footnotes-footnote__note\" tabindex=\"0\" data-mfn=\"3\">[Band 3: Dialektik der Aufkl\u00e4rung: Begriff der Aufkl\u00e4rung. Theodor W. Adorno: Gesammelte Schriften, S. 1107 (vgl. GS 3, S. 20) http:\/\/www.digitale-bibliothek.de\/band97.htm ]<\/span><\/p>\n<\/blockquote>\n<p>Das Manifest will etwas Gutes, aber es f\u00fchrt in die Irre. Was einen aber wundert, ist, dass der Glaube an die Verbesserung der Welt durch die Technik so schrecklich auftrumpft, als habe man den Kern solcher Anschauungen nie gesehen. Vom Denken her scheint es mit dem Web2.0 eher in Richtung Dampfmaschine zur\u00fcckzugehen, denn das Rad hatte man nicht neu erfinden k\u00f6nnen. Es rollt weiterhin in die falsche Richtung. Mit jungem Schwung.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Manifeste%20Geschw%C3%A4tzigkeitsleere https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Manifeste%20Geschw%C3%A4tzigkeitsleere https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Manifeste%20Geschw%C3%A4tzigkeitsleere%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div><h3 class=\"modern-footnotes-list-heading \">Fussnoten:<\/h3><ul class=\"modern-footnotes-list \"><li><span>1<\/span><div>[Band 3: Dialektik der Aufkl\u00e4rung: Begriff der Aufkl\u00e4rung. Theodor W. Adorno: Gesammelte Schriften, S. 1105 (vgl. GS 3, S. 19) http:\/\/www.digitale-bibliothek.de\/band97.htm ]<\/div><\/li><li><span>2<\/span><div>[Band 3: Dialektik der Aufkl\u00e4rung: Begriff der Aufkl\u00e4rung. Theodor W. Adorno: Gesammelte Schriften, S. 1105 (vgl. GS 3, S. 19) http:\/\/www.digitale-bibliothek.de\/band97.htm ]<\/div><\/li><li><span>3<\/span><div>[Band 3: Dialektik der Aufkl\u00e4rung: Begriff der Aufkl\u00e4rung. Theodor W. Adorno: Gesammelte Schriften, S. 1107 (vgl. GS 3, S. 20) http:\/\/www.digitale-bibliothek.de\/band97.htm ]<\/div><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Seit je hat Aufkl\u00e4rung im umfassendsten Sinn fortschreitenden Denkens das Ziel verfolgt, von den Menschen die Furcht zu nehmen und sie als Herren einzusetzen. Aber die vollends aufgekl\u00e4rte Erde strahlt im Zeichen triumphalen Unheils.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Manifeste%20Geschw%C3%A4tzigkeitsleere https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Manifeste%20Geschw%C3%A4tzigkeitsleere https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Manifeste%20Geschw%C3%A4tzigkeitsleere%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2009%2F09%2Fvielfalt-durch-geschwaetzigkeit%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":7410,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2648],"tags":[1746,1817,2315],"class_list":["post-2620","post","type-post","status-publish","format-standard","hentry","category-dieurteilskraft","tag-aufklrung","tag-bloggen","tag-internet","entry"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifeste Geschw\u00e4tzigkeitsleere - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifeste Geschw\u00e4tzigkeitsleere - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Seit je hat Aufkl\u00e4rung im umfassendsten Sinn fortschreitenden Denkens das Ziel verfolgt, von den Menschen die Furcht zu nehmen und sie als Herren einzusetzen. Aber die vollends aufgekl\u00e4rte Erde strahlt im Zeichen triumphalen Unheils.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-15T08:44:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T07:48:13+00:00\" \/>\n<meta name=\"author\" content=\"huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/\"},\"author\":{\"name\":\"huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\"},\"headline\":\"Manifeste Geschw\u00e4tzigkeitsleere\",\"datePublished\":\"2009-09-15T08:44:18+00:00\",\"dateModified\":\"2023-12-18T07:48:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/\"},\"wordCount\":1041,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"keywords\":[\"Aufkl\u00e4rung\",\"Bloggen\",\"Internet\"],\"articleSection\":[\"die Urteilskraft\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/\",\"name\":\"Manifeste Geschw\u00e4tzigkeitsleere - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"datePublished\":\"2009-09-15T08:44:18+00:00\",\"dateModified\":\"2023-12-18T07:48:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2009\\\/09\\\/vielfalt-durch-geschwaetzigkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifeste Geschw\u00e4tzigkeitsleere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\",\"name\":\"huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"caption\":\"huflaikhan\"},\"description\":\"Musikwissenschaftler, Ideologiekritiker seit 1964.\",\"sameAs\":[\"https:\\\/\\\/kritische-masse.de\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/huflaikhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifeste Geschw\u00e4tzigkeitsleere - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/","og_locale":"de_DE","og_type":"article","og_title":"Manifeste Geschw\u00e4tzigkeitsleere - Kritische Masse","og_description":"Seit je hat Aufkl\u00e4rung im umfassendsten Sinn fortschreitenden Denkens das Ziel verfolgt, von den Menschen die Furcht zu nehmen und sie als Herren einzusetzen. Aber die vollends aufgekl\u00e4rte Erde strahlt im Zeichen triumphalen Unheils.","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2009-09-15T08:44:18+00:00","article_modified_time":"2023-12-18T07:48:13+00:00","author":"huflaikhan","twitter_misc":{"Verfasst von":"huflaikhan","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/"},"author":{"name":"huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932"},"headline":"Manifeste Geschw\u00e4tzigkeitsleere","datePublished":"2009-09-15T08:44:18+00:00","dateModified":"2023-12-18T07:48:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/"},"wordCount":1041,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"keywords":["Aufkl\u00e4rung","Bloggen","Internet"],"articleSection":["die Urteilskraft"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/","name":"Manifeste Geschw\u00e4tzigkeitsleere - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"datePublished":"2009-09-15T08:44:18+00:00","dateModified":"2023-12-18T07:48:13+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/vielfalt-durch-geschwaetzigkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"Manifeste Geschw\u00e4tzigkeitsleere"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932","name":"huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","caption":"huflaikhan"},"description":"Musikwissenschaftler, Ideologiekritiker seit 1964.","sameAs":["https:\/\/kritische-masse.de"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/huflaikhan\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":["die Urteilskraft"],"post_class":[["post-2620","post","type-post","status-publish","format-standard","hentry","category-dieurteilskraft","tag-aufklrung","tag-bloggen","tag-internet","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":8366,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/09\/manifeste-geschwaetzigkeitsleere-zum-internet-manifest-von-2009\/","url_meta":{"origin":2620,"position":0},"title":"Manifeste Geschw\u00e4tzigkeitsleere [Zum Internet-Manifest von 2009]","author":"der huflaikhan","date":"15. September 2009","format":false,"excerpt":"In gewissem Sinne f\u00fchlt man sich an bestimmte Stellen aus der sozialphilosophischen Literatur erinnert, wenn man sich durch den Strudel der Publikationen im Internet hindurchw\u00fchlt. Insbesondere an die \"Dialektik der Aufkl\u00e4rung\" mag man da leicht denken k\u00f6nnen. \"Seit je hat Aufkl\u00e4rung im umfassendsten Sinn fortschreitenden Denkens das Ziel verfolgt, von\u2026","rel":"","context":"In &quot;das Netz&quot;","block_context":{"text":"das Netz","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/dasnetz\/"},"img":{"alt_text":"Carlos Bica","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2005\/06\/20050601-bica-group-bica1.jpg?fit=500%2C375&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2193,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/05\/pour-kalt-mamsell\/","url_meta":{"origin":2620,"position":1},"title":"Pour Kalt Mamsell","author":"hufi","date":"12. Mai 2007","format":false,"excerpt":"Die Welt ist doch recht einsam geworden. Der Menschheitsplagen gibt es viele zu tragen. Demn\u00e4chst beginnt meine Eigen\u00f6strogen-Behandlung. Immerfort muss ich weinen. Warum? Mir fehlt die innere Abfahrt. Am Himmel platzen die Sterne. Es gibt zu viel Celluloid auf der Erde. \"Schlafende Hormone soll man nicht wecken.\" \"Du sollst nicht\u2026","rel":"","context":"Mit 9 Kommentaren","block_context":{"text":"Mit 9 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/05\/pour-kalt-mamsell\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3331,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/03\/massenkultur-vorgef-hl-eines-nichtgef-hls\/","url_meta":{"origin":2620,"position":2},"title":"Massenkultur \u2013 Vorgef\u00fchl eines Nichtgef\u00fchls","author":"huflaikhan","date":"1. M\u00e4rz 2014","format":false,"excerpt":"Ein Pl\u00e4doyer f\u00fcr das langweilige Bild \u201eMassenkultur ist ungeschminkte Schminke.\u201c Da f\u00e4llt mir jetzt grad auch nichts mehr zu ein. \u201eKitsch ist der Niederschlag entwerteter Formen und Floskeln in einer Formwelt, die ihrem Umkreis entr\u00fcckt ist. Was der Kunst von ehemals zugeh\u00f6rte und heute unternommen wird, rechnet zum Kitsch.\u201c Es\u2026","rel":"","context":"In \"Adorno\"","block_context":{"text":"Adorno","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/adorno\/"},"img":{"alt_text":"Aufruhr im Wald. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/03\/gerichtsmedizin.jpg?fit=800%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/03\/gerichtsmedizin.jpg?fit=800%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/03\/gerichtsmedizin.jpg?fit=800%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/03\/gerichtsmedizin.jpg?fit=800%2C801&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2050,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/05\/kalenderblatt-juni-2007\/","url_meta":{"origin":2620,"position":3},"title":"Kalenderblatt Juni 2007","author":"huflaikhan","date":"31. Mai 2007","format":false,"excerpt":"Nur solche Gedanken bieten der allm\u00e4chtigen Ohnmacht des sicheren Einverst\u00e4ndnisses die Stirn, die bis zum \u00c4u\u00dfersten gehen; \u0085 [Band 6: Negative Dialektik. Jargon der Eigentlichkeit: Einleitung. Theodor W. Adorno: Gesammelte Schriften, S. 2880 (vgl. GS 6, S. 45) http:\/\/www.digitale-bibliothek.de\/band97.htm ]","rel":"","context":"Mit 3 Kommentaren","block_context":{"text":"Mit 3 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/05\/kalenderblatt-juni-2007\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8418,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/03\/ein-plaedoyer-fuer-das-langweilige-bild\/","url_meta":{"origin":2620,"position":4},"title":"Ein Pl\u00e4doyer f\u00fcr das langweilige Bild","author":"der huflaikhan","date":"1. M\u00e4rz 2014","format":false,"excerpt":"\u201eMassenkultur ist ungeschminkte Schminke.\u201c Da f\u00e4llt mir jetzt grad auch nichts mehr zu ein. \u201eKitsch ist der Niederschlag entwerteter Formen und Floskeln in einer Formwelt, die ihrem Umkreis entr\u00fcckt ist. Was der Kunst von ehemals zugeh\u00f6rte und heute unternommen wird, rechnet zum Kitsch.\u201c Es ist der Ekel,\u00a0 der mir in\u2026","rel":"","context":"In &quot;die Kunst&quot;","block_context":{"text":"die Kunst","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/die-kunst\/"},"img":{"alt_text":"Gerichtsmedizin. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/03\/gerichtsmedizin.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/03\/gerichtsmedizin.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/03\/gerichtsmedizin.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":2866,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/02\/seite-118342\/","url_meta":{"origin":2620,"position":5},"title":"Seite 118342","author":"der huflaikhan","date":"26. Februar 2009","format":false,"excerpt":"Gustav Falke, ein Name, der mir eigentlich gar nichts sagt. Auch wenn es nur schwer geht, dass man in einer digitalen Bibliothek st\u00f6bert, muss man das ab und zu machen. Solche komischen Dinge kann man dann da finden. Gebet \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Herr, la\u00df mich hungern dann und wann,\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Satt sein macht\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/2620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=2620"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/2620\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=2620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=2620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=2620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}