{"id":2665,"date":"2012-08-07T13:55:33","date_gmt":"2012-08-07T12:55:33","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/"},"modified":"2023-12-21T10:38:39","modified_gmt":"2023-12-21T09:38:39","slug":"gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/","title":{"rendered":"GEMA sch\u00fctzt ihre Urheber &#8211; andere sind ihr einigerma\u00dfen egal"},"content":{"rendered":"<p>GEMA: Wir kosten was, brauchen aber kostenfreies Material. Urheber gibt es in zwei Klassen. Die, die man gegen die b\u00f6se Welt sch\u00fctzen will und die, die einem egal sind.<\/p>\n<p>Neulich habe ich eine Mail der Redaktion <a href=\"https:\/\/www.gema.de\/presse\/pressemitteilungen\/presse-details\/article\/virtuos-das-magazin-der-gema-erste-ausgabe-der-neuen-gema-printpublikation-erschienen.html\">&#8220;virtuos&#8221;<\/a> &#8211; der Mitgliederzeitschrift der <a href=\"http:\/\/www.gema.de\">GEMA<\/a>\u00a0\u2013 erhalten. Darin fragte man an, ob man ein Foto von Peter Michael Hamel verwenden d\u00fcrfe, das ich einmal w\u00e4hrend einer taktlos-Sendung gemacht hatte. Das ist gut und nett. Man bittet um die Erlaubnis des Nachdrucks und die richtige Form der Fotografennennung, \u00a0also, wer machte das Foto. Eine Tanja F. wurde dann pr\u00e4ziser:<\/p>\n<blockquote><p>Hierf\u00fcr sind wir auf der Suche nach einem passenden, <strong>kostenfreien<\/strong> Foto.<\/p><\/blockquote>\n<p>Das Ansinnen ist ja nicht f\u00fcr sich falsch sondern freundlich und nicht ungew\u00f6hnlich. Nat\u00fcrlich darf man das fragen. Nur, ob es besonders geschickt ist, die eigene Klientel vor nicht lizenzierter, kostenloser Nutzung zu sch\u00fctzen, andere das aber mal abzufragen, ist nicht so recht einzusehen f\u00fcr eine Organsisation, die sich selbst als Inkassounternehmen versteht und nicht als Samariter. Es wirkt unglaubw\u00fcrdig.<\/p>\n<p>Urheber schaden Urhebern solange man sich nicht selbst schadet.<\/p>\n<p>Ich habe der Redakteurin meine Verwunderung mitgeteilt und bin in bester Erwartung eines sicher sehr fairen Angebots von ihrer Seite. Ebenso von der Pressestelle der GEMA.<\/p>\n<p>PS: Lieber Peter Michael Hamel, f\u00fcr deinen Geburtstag h\u00e4tte ich das Foto nat\u00fcrlich auch so rausger\u00fcckt. Aber du bist ja selbst Urheber und muss von deiner kompositorischen Arbeit wenigstens zum Teil leben.<\/p>\n<p>PPS: Was liest man da in der Ank\u00fcndigung der letzten virtuos? \u201eRespekt vor dem sch\u00f6pferischen Akt als solchem?\u201c<\/p>\n<blockquote><p>In Zeiten, in denen immer wieder Forderungen nach einer Einschr\u00e4nkung bis hin zu einer v\u00f6lligen Abschaffung des Urheberrechts laut werden, setzt der Deutsche Musikautorenpreis ein wichtiges Zeichen: \u201eDenn er ist nicht nur Ausdruck der Solidarit\u00e4t innerhalb der GEMA\u201c, so Dr. Harald Heker, der Vorstandsvorsitzende der Verwertungsgesellschaft, bei der diesj\u00e4hrigen Preisverleihung im Berliner Hotel Ritz-Carlton, \u201esondern auch ein Symbol des Respekts vor dem sch\u00f6pferischen Akt als solchem.\u201c (<a href=\"http:\/\/www.heller-partner.de\/news\/article\/ausgezeichnete-gemeinschaft\/\">Quelle<\/a>)<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GEMA: Wir kosten was, brauchen aber kostenfreies Material. Urheber gibt es in zwei Klassen. Die, die man gegen die b\u00f6se Welt sch\u00fctzen will und die, die einem egal sind. Neulich habe ich eine Mail der Redaktion &#8220;virtuos&#8221; &#8211; der Mitgliederzeitschrift der GEMA\u00a0\u2013 erhalten. Darin fragte man an, ob man ein Foto von Peter Michael Hamel [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":2142,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2647,2673,2652,2655,2654],"tags":[2087,2147,2670],"class_list":["post-2665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angriffauf","category-das-urheberrecht","category-diemusik","category-ich","category-privates","tag-fotografie","tag-gema","tag-urheberrecht","entry","has-media"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GEMA sch\u00fctzt ihre Urheber - andere sind ihr einigerma\u00dfen egal - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GEMA sch\u00fctzt ihre Urheber - andere sind ihr einigerma\u00dfen egal - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"GEMA: Wir kosten was, brauchen aber kostenfreies Material. Urheber gibt es in zwei Klassen. Die, die man gegen die b\u00f6se Welt sch\u00fctzen will und die, die einem egal sind. Neulich habe ich eine Mail der Redaktion &#8220;virtuos&#8221; &#8211; der Mitgliederzeitschrift der GEMA\u00a0\u2013 erhalten. Darin fragte man an, ob man ein Foto von Peter Michael Hamel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2012-08-07T12:55:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T09:38:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"759\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/\"},\"author\":{\"name\":\"huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\"},\"headline\":\"GEMA sch\u00fctzt ihre Urheber &#8211; andere sind ihr einigerma\u00dfen egal\",\"datePublished\":\"2012-08-07T12:55:33+00:00\",\"dateModified\":\"2023-12-21T09:38:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/mao.jpg?fit=1600%2C759&ssl=1\",\"keywords\":[\"Fotografie\",\"GEMA\",\"Urheberrecht\"],\"articleSection\":[\"Angriff auf \u2026\",\"das Urheberrecht\",\"die Musik\",\"Ich\",\"Privates\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/\",\"name\":\"GEMA sch\u00fctzt ihre Urheber - andere sind ihr einigerma\u00dfen egal - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/mao.jpg?fit=1600%2C759&ssl=1\",\"datePublished\":\"2012-08-07T12:55:33+00:00\",\"dateModified\":\"2023-12-21T09:38:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/mao.jpg?fit=1600%2C759&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2012\\\/08\\\/mao.jpg?fit=1600%2C759&ssl=1\",\"width\":1600,\"height\":759,\"caption\":\"Peter Michael Hamels Arbeitsplatz. Foto: Hufner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2012\\\/08\\\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GEMA sch\u00fctzt ihre Urheber &#8211; andere sind ihr einigerma\u00dfen egal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\",\"name\":\"huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"caption\":\"huflaikhan\"},\"description\":\"Musikwissenschaftler, Ideologiekritiker seit 1964.\",\"sameAs\":[\"https:\\\/\\\/kritische-masse.de\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/huflaikhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GEMA sch\u00fctzt ihre Urheber - andere sind ihr einigerma\u00dfen egal - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/","og_locale":"de_DE","og_type":"article","og_title":"GEMA sch\u00fctzt ihre Urheber - andere sind ihr einigerma\u00dfen egal - Kritische Masse","og_description":"GEMA: Wir kosten was, brauchen aber kostenfreies Material. Urheber gibt es in zwei Klassen. Die, die man gegen die b\u00f6se Welt sch\u00fctzen will und die, die einem egal sind. Neulich habe ich eine Mail der Redaktion &#8220;virtuos&#8221; &#8211; der Mitgliederzeitschrift der GEMA\u00a0\u2013 erhalten. Darin fragte man an, ob man ein Foto von Peter Michael Hamel [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2012-08-07T12:55:33+00:00","article_modified_time":"2023-12-21T09:38:39+00:00","og_image":[{"width":1600,"height":759,"url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg","type":"image\/jpeg"}],"author":"huflaikhan","twitter_misc":{"Verfasst von":"huflaikhan","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/"},"author":{"name":"huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932"},"headline":"GEMA sch\u00fctzt ihre Urheber &#8211; andere sind ihr einigerma\u00dfen egal","datePublished":"2012-08-07T12:55:33+00:00","dateModified":"2023-12-21T09:38:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/"},"wordCount":353,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg?fit=1600%2C759&ssl=1","keywords":["Fotografie","GEMA","Urheberrecht"],"articleSection":["Angriff auf \u2026","das Urheberrecht","die Musik","Ich","Privates"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/","name":"GEMA sch\u00fctzt ihre Urheber - andere sind ihr einigerma\u00dfen egal - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#primaryimage"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg?fit=1600%2C759&ssl=1","datePublished":"2012-08-07T12:55:33+00:00","dateModified":"2023-12-21T09:38:39+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#primaryimage","url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg?fit=1600%2C759&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg?fit=1600%2C759&ssl=1","width":1600,"height":759,"caption":"Peter Michael Hamels Arbeitsplatz. Foto: Hufner"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/gema-sch-tzt-ihrer-urheber-andere-sind-ihr-einigerma-en-egal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"GEMA sch\u00fctzt ihre Urheber &#8211; andere sind ihr einigerma\u00dfen egal"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932","name":"huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","caption":"huflaikhan"},"description":"Musikwissenschaftler, Ideologiekritiker seit 1964.","sameAs":["https:\/\/kritische-masse.de"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/huflaikhan\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/mao.jpg?fit=1600%2C759&ssl=1","categories_names":["Angriff auf \u2026","das Urheberrecht","die Musik","Ich","Privates"],"post_class":[["post-2665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angriffauf","category-das-urheberrecht","category-diemusik","category-ich","category-privates","tag-fotografie","tag-gema","tag-urheberrecht","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":3112,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/vom-nutzen-der-doppelmoral\/","url_meta":{"origin":2665,"position":0},"title":"Vom Nutzen der Doppelmoral","author":"huflaikhan","date":"4. August 2012","format":false,"excerpt":"Gedanken zur urheberrechtlichen Doppelmoral bei Organisationen, die angeblich f\u00fcr ein starkes Urheberrecht k\u00e4mpfen. Vorank\u00fcndigung. Deutscher Kulturrat und GEMA. Ich \u00fcberleg schon seit ein paar Tagen, ob ich ein paar Beispiele aus dem Bereich urheberrechtlicher Doppelmoral anhand zweier Organisationen aufschreiben soll. Wenn nur die Dokumentation nicht\u00a0so aufw\u00e4ndig w\u00e4re? a) Der Deutsche\u2026","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Doppelblick statt Doppelmoral. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/autobahn-0079.jpg?fit=1067%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/autobahn-0079.jpg?fit=1067%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/autobahn-0079.jpg?fit=1067%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/autobahn-0079.jpg?fit=1067%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/autobahn-0079.jpg?fit=1067%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8852,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2021\/12\/kreative-in-artgerechter-haltung\/","url_meta":{"origin":2665,"position":1},"title":"Kreative in artgerechter Haltung","author":"der huflaikhan","date":"15. Dezember 2021","format":false,"excerpt":"Es ist sehr interessant, dass die Firma Apple beim Kauf ihrer Telefone angibt, welchen Anteil die Urheberrechtsabgabe am Kuafpreis hat. F\u00fcr ein aktuelles iPhone 13 Pro zum Preis von 1269,00 Euro (bei 256 GB Speicher) werden sage und schreibe satte f\u00fcnf Euro f\u00e4llig. Das entspricht aufgerundet 0,4% des Gesamt-Kaufpreises \u2013\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"opfer m\u00fcssen begracht werden. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8541,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2015\/05\/grosser-wunderlicher\/","url_meta":{"origin":2665,"position":2},"title":"Gro\u00dfer Wunderlicher &#8230;","author":"der huflaikhan","date":"20. Mai 2015","format":false,"excerpt":"Der Chefredakteur der MusikWoche ist ulkig geworden. Er beschw\u00f6rt in letzter Zeit die Bedeutung der GEMA in einigen Texten in einer Weise, die nachdenklich macht, weil sie so schief sind. \u201eSelbstverst\u00e4ndlich gibt es oft genug berechtigte Anl\u00e4sse f\u00fcr Kritik \u2013 es w\u00e4re unheimlich, w\u00fcrde ein solcher Apparat v\u00f6llig ger\u00e4usch- und\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"Schiller war schon schlauer. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/05\/zusatz-0367-199x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8604,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2015\/12\/urheberrecht\/","url_meta":{"origin":2665,"position":3},"title":"Die Wunder des Urheberrechts","author":"der huflaikhan","date":"21. Dezember 2015","format":false,"excerpt":"Es ist egal, was hinten rauskommt, so muss man wohl ein Urteil des Bundesgerichtshofs (BGH) interpretieren, das j\u00fcngst ergangen ist. Danach wollte die GEMA von einem Hotelbetreiber, der Fernseher in seinen R\u00e4umen stehen hat, die terrestrisch gesendete Signale aufnehmen, auf Zahlung einer gewissen Summe in Anspruch nehmen. In den Vorverfahren\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10841,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2025\/04\/gema-kulturreform-eine-kleine-umfrage\/","url_meta":{"origin":2665,"position":4},"title":"GEMA-Kulturreform \u2013 eine kleine Umfrage","author":"der huflaikhan","date":"5. April 2025","format":false,"excerpt":"Um ein kleines Stimmungsbild zu bekommen, habe ich mich entschlossen, eine Umfrage in Sachen GEMA-Kultur-Reform zu machen. Daf\u00fcr gibt es einen Link, einen QR-Code und die M\u00f6glichkeit, dies hier direkt im Browser auszuf\u00fcllen. Die Umfrage ist anonym. \u00dcber eine Teilnahme w\u00fcrde ich mich freuen.","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Speersitz statt Sperrspitz. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/08\/sperrsitz-anders.webp?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/08\/sperrsitz-anders.webp?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/08\/sperrsitz-anders.webp?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/08\/sperrsitz-anders.webp?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8245,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/06\/pauschalverguetungen-fuers-netz-2\/","url_meta":{"origin":2665,"position":5},"title":"Pauschalverg\u00fctungen f\u00fcrs Netz","author":"der huflaikhan","date":"22. Juni 2004","format":false,"excerpt":"Langsam formieren sich die Verfechter des Prinzips der Pauschalverg\u00fctung f\u00fcr urheberrechtlich gesch\u00fctzte Werke im Internet. Ganz druckfrisch ist eine Stellungnahme unter dem Titel \u201cKompensation ohne Kontrolle\u201d (Stellungnahme zum Zweiten Korb der Novellierung des Urheberrechtsgesetzes) ander beteiligt sind: privatkopie.net, Forum Informatikerinnen f\u00fcr Frieden und gesellschaftliche Verantwortung e.V.(FIfF), Netzwerk Neue Medien, Chaos\u2026","rel":"","context":"In &quot;das Recht&quot;","block_context":{"text":"das Recht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-recht\/"},"img":{"alt_text":"Privatkopie. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/2665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=2665"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/2665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media\/2666"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=2665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=2665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=2665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}