{"id":3306,"date":"2014-01-14T07:04:46","date_gmt":"2014-01-14T06:04:46","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/zettelkasten\/geschichte-wiederholt-sich-als-trag-die\/"},"modified":"2023-12-20T09:10:18","modified_gmt":"2023-12-20T08:10:18","slug":"geschichte-wiederholt-sich-als-trag-die","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/","title":{"rendered":"Geschichte wiederholt sich als Trag\u00f6die"},"content":{"rendered":"<p>Und so ist vielleicht die aktuelle Technikgl\u00e4ubig- und verlorenheit nichts anderes als Wiederkehr des italienischen Futurismus, nur auf auf amerikanisch.<\/p>\n<p>Pr\u00e4ziser m\u00fcsste man sagen: \u201eGeschichte wiederholt sich als Trag\u00f6die der Trag\u00f6die.\u201c<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Und so ist vielleicht die aktuelle Technikgl\u00e4ubig- und verlorenheit nichts anderes als Wiederkehr des italienischen Futurismus, nur auf auf amerikanisch. Pr\u00e4ziser m\u00fcsste man sagen: \u201eGeschichte wiederholt sich als Trag\u00f6die der Trag\u00f6die.\u201c &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":3307,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":243,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2647,2651,2648,2667],"tags":[2163,2315],"class_list":["post-3306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angriffauf","category-dasnetz","category-dieurteilskraft","category-zettelkasten","tag-geschichte","tag-internet","entry","has-media"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geschichte wiederholt sich als Trag\u00f6die - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geschichte wiederholt sich als Trag\u00f6die - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Und so ist vielleicht die aktuelle Technikgl\u00e4ubig- und verlorenheit nichts anderes als Wiederkehr des italienischen Futurismus, nur auf auf amerikanisch. Pr\u00e4ziser m\u00fcsste man sagen: \u201eGeschichte wiederholt sich als Trag\u00f6die der Trag\u00f6die.\u201c &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-14T06:04:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T08:10:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"huflaikhan\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/\"},\"author\":{\"name\":\"huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\"},\"headline\":\"Geschichte wiederholt sich als Trag\u00f6die\",\"datePublished\":\"2014-01-14T06:04:46+00:00\",\"dateModified\":\"2023-12-20T08:10:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/\"},\"wordCount\":43,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1\",\"keywords\":[\"Geschichte\",\"Internet\"],\"articleSection\":[\"Angriff auf \u2026\",\"das Netz\",\"die Urteilskraft\",\"Zettelkasten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/\",\"name\":\"Geschichte wiederholt sich als Trag\u00f6die - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1\",\"datePublished\":\"2014-01-14T06:04:46+00:00\",\"dateModified\":\"2023-12-20T08:10:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1\",\"width\":2560,\"height\":1696,\"caption\":\"In der Bar zur Zukunft. Foto: Hufner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2014\\\/01\\\/geschichte-wiederholt-sich-als-trag-die\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Geschichte wiederholt sich als Trag\u00f6die\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\",\"name\":\"huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"caption\":\"huflaikhan\"},\"description\":\"Musikwissenschaftler, Ideologiekritiker seit 1964.\",\"sameAs\":[\"https:\\\/\\\/kritische-masse.de\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/huflaikhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geschichte wiederholt sich als Trag\u00f6die - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/","og_locale":"de_DE","og_type":"article","og_title":"Geschichte wiederholt sich als Trag\u00f6die - Kritische Masse","og_description":"Und so ist vielleicht die aktuelle Technikgl\u00e4ubig- und verlorenheit nichts anderes als Wiederkehr des italienischen Futurismus, nur auf auf amerikanisch. Pr\u00e4ziser m\u00fcsste man sagen: \u201eGeschichte wiederholt sich als Trag\u00f6die der Trag\u00f6die.\u201c &nbsp;","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2014-01-14T06:04:46+00:00","article_modified_time":"2023-12-20T08:10:18+00:00","og_image":[{"width":2560,"height":1696,"url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg","type":"image\/jpeg"}],"author":"huflaikhan","twitter_misc":{"Verfasst von":"huflaikhan"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/"},"author":{"name":"huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932"},"headline":"Geschichte wiederholt sich als Trag\u00f6die","datePublished":"2014-01-14T06:04:46+00:00","dateModified":"2023-12-20T08:10:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/"},"wordCount":43,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1","keywords":["Geschichte","Internet"],"articleSection":["Angriff auf \u2026","das Netz","die Urteilskraft","Zettelkasten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/","name":"Geschichte wiederholt sich als Trag\u00f6die - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#primaryimage"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1","datePublished":"2014-01-14T06:04:46+00:00","dateModified":"2023-12-20T08:10:18+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#primaryimage","url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1","width":2560,"height":1696,"caption":"In der Bar zur Zukunft. Foto: Hufner"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/01\/geschichte-wiederholt-sich-als-trag-die\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"Geschichte wiederholt sich als Trag\u00f6die"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932","name":"huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","caption":"huflaikhan"},"description":"Musikwissenschaftler, Ideologiekritiker seit 1964.","sameAs":["https:\/\/kritische-masse.de"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/huflaikhan\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/01\/taktlos164-6094-scaled.jpg?fit=2560%2C1696&ssl=1","categories_names":["Angriff auf \u2026","das Netz","die Urteilskraft","Zettelkasten"],"post_class":[["post-3306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angriffauf","category-dasnetz","category-dieurteilskraft","category-zettelkasten","tag-geschichte","tag-internet","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":8829,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/09\/flexible-vergangenheit-und-gegenwart\/","url_meta":{"origin":3306,"position":0},"title":"Flexible Vergangenheit und Gegenwart","author":"der huflaikhan","date":"7. September 2020","format":false,"excerpt":"Volker Brauns \"Berichte von Hinze und Kunze\" z\u00e4hlen f\u00fcr mich sowieso zu den Perlen deutscher Vorvereinigungsliteratur. Da bl\u00e4ttert man sich durch und findet fast immer einen Gedanken, den man sich einmal genauer ansehen sollte. Harmlose Kritik.Manches, das Hinze mi\u00dffiel, lehnte er nicht rundheraus ab, er kratzte nur am Lack. Vor\u2026","rel":"","context":"In &quot;die Kunst&quot;","block_context":{"text":"die Kunst","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/die-kunst\/"},"img":{"alt_text":"Schutzgebiet: Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/02\/schutzgebiet-1024x678.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/02\/schutzgebiet-1024x678.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/02\/schutzgebiet-1024x678.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2020\/02\/schutzgebiet-1024x678.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1364,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/08\/kurze-geschichte-2005-jugenddemenz\/","url_meta":{"origin":3306,"position":1},"title":"Kurze Geschichte 2005 &#8211; Jugenddemenz","author":"huflaikhan","date":"14. August 2005","format":false,"excerpt":"Ich habe den Stein der Weisen gefunden. Jetzt habe ich ihn wieder verlegt. Weitere Demenzen.","rel":"","context":"Mit 1 Kommentar","block_context":{"text":"Mit 1 Kommentar","link":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/08\/kurze-geschichte-2005-jugenddemenz\/#comments"},"img":{"alt_text":"Stein der Weisen.","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2005\/08\/20050814-steinderweisen-500.jpg?fit=500%2C335&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":10612,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2025\/01\/man-kann-es-auch-uebertreiben-newsfirestorm\/","url_meta":{"origin":3306,"position":2},"title":"Man kann es auch \u00fcbertreiben \u2026 (Newsfirestorm)","author":"der huflaikhan","date":"16. Januar 2025","format":false,"excerpt":"Diese Newsraserei ist auch gesellschafts- und klimasch\u00e4dlich. +++ Eine gem\u00fctliche Sofaecke im Pott +++ Der Mensch ist Staub +++ Verbrechen in Kleinmachnow +++ Noten biologisch +++","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"#Kunst vorm Bau. Eine gem\u00fctliche Sofaecke im Pott. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/01\/kunstvormbau.jpg?fit=1080%2C939&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/01\/kunstvormbau.jpg?fit=1080%2C939&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/01\/kunstvormbau.jpg?fit=1080%2C939&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/01\/kunstvormbau.jpg?fit=1080%2C939&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/01\/kunstvormbau.jpg?fit=1080%2C939&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8434,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/06\/erfindung-des-fussballs-und-wm-pleiten\/","url_meta":{"origin":3306,"position":3},"title":"Erfindung des Fussballs \u2026 und WM-Pleiten","author":"der huflaikhan","date":"19. Juni 2014","format":false,"excerpt":"Raus, raus, raus. Spanien ist raus, Kamerun ist raus. Typisch f\u00fcr die WM in Brasilien: die falschen Favoriten plumpsen in den Orkus der WM-Geschichte. Wie das insgesamt funktioniert, zeigte sich beim Tippspiel der nmz. Alle bis auf einen Tipper (icke n\u00e4mlich) haben einen Sieg Spaniens gegen Chile getippt. Der PFIFA-Weltranglisten\u2026","rel":"","context":"In &quot;die Urteilskraft&quot;","block_context":{"text":"die Urteilskraft","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/dieurteilskraft\/"},"img":{"alt_text":"Tippspiel 2014-06-19 11-18-09","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/2014\/06\/Tippspiel_2014-06-19_11-18-09.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":641,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/08\/kulturaustausch-mediterran\/","url_meta":{"origin":3306,"position":4},"title":"Kulturaustausch &#8211; mediterran","author":"huflaikhan","date":"3. August 2004","format":false,"excerpt":"Gestern blieb es hier etwas stumm, denn eine Redaktionssitzung forderte mich heraus. Sie wurde typischerweise zu einer Ein-Tages-Klausur. Ertragreich, streitvoll, jedoch gerne konstruktiv. Da ich gestern bester b\u00f6ser Laune war, stellte ich wieder mal fast jedes Thema infrage. Irgendwann kam es zum Komplex EU-Kultur und Kulturaustausch. Ein heftiger Schlagabtausch zog\u2026","rel":"","context":"In \"Braudel\"","block_context":{"text":"Braudel","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/braudel\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":84,"url":"https:\/\/www.kritische-masse.de\/logbuch\/1998\/06\/komposition-und-film\/","url_meta":{"origin":3306,"position":5},"title":"Komposition und Film","author":"huflaikhan","date":"15. Juni 1998","format":false,"excerpt":"\u201eComposing for the Films: Adorno, Eisler and the sociology of music\"(Historical Journal of Film, Radio and Television, Vol.18, No.4, 1998I. Komposition f\u00fcr den Film \u2013 Entstehung, \u00c4sthetik, SoziologieWenn man verallgemeinernd annimmt, da\u00df mit bestimmten historischen Situationen zugleich deren Analysen vom Verfall betroffen sind, so wird auch ein altes Buch veralten.\u2026","rel":"","context":"In &quot;Texte&quot;","block_context":{"text":"Texte","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/texte\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/3306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=3306"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/3306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media\/3307"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=3306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=3306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=3306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}