{"id":749,"date":"2004-09-14T19:49:41","date_gmt":"2004-09-14T18:49:41","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/"},"modified":"2023-12-18T08:49:46","modified_gmt":"2023-12-18T07:49:46","slug":"aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/","title":{"rendered":"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div><p>Ich unterschreibe wirklich nicht gerne. Aber in diesem Fall gerne. Die &#8220;G\u00f6ttinger Erkl\u00e4rung zum Urheberrecht f\u00fcr Bildung und Wissenschaft vom 5. Juli 2004&#8221;.<br \/>\n<!--break--><br \/>\n<cite>Mit der Antwort auf die Frage &quot;Wie zug\u00e4nglich sind Wissen und Information?&quot; wird entschieden \u00fcber die Bildungs- und Entwicklungschancen jedes einzelnen B\u00fcrgers in der Informationsgesellschaft wie auch \u00fcber die Chancen k\u00fcnftiger Generationen, auf dem vorhandenen Wissen aufbauen zu k\u00f6nnen. Die im Urheberrechtsgesetz (UrhG) getroffenen gesetzlichen Regelungen haben nachhaltigen Einfluss darauf, ob sich in unserer Gesellschaft offene, vernetzte Kommunikations- und Informationsstrukturen entwickeln k\u00f6nnen. Sie entscheiden damit auch \u00fcber die Qualit\u00e4t unseres Bildungssystems, \u00fcber die Inventionsf\u00e4higkeit der Wissenschaft und die Innovationskraft der Wirtschaft. Im globalen Wettbewerb sind sie die wesentlichen Faktoren f\u00fcr eine prosperierende soziale, kulturelle und \u00f6konomische Entwicklung und damit f\u00fcr die Zukunft unserer Gesellschaft.<\/p>\n<p>Bei der Umsetzung der Richtlinie 2001\/29\/EG in das Urheberrecht hat der Gesetzgeber bisher vornehmlich die Belange der Rechteverwerter zur kommerziellen Nutzung der digitalen Medien und der Netze als zus\u00e4tzliche Vertriebswege ber\u00fccksichtigt. Im Vordergrund standen vor allem die Vermeidung von Risiken f\u00fcr die private Rechteverwertung und nicht die Nutzung der mit den neuen technischen Medien verbundenen Chancen f\u00fcr die Allgemeinheit. Dies gilt insbesondere f\u00fcr den Bereich von Bildung und Wissenschaft. Die Informationsgesellschaft bietet hier neue Potenziale der Wissensvermittlung und der Zusammenarbeit von Wissenschaftlerinnen und Wissenschaftlern. Die Nutzung dieser neuen M\u00f6glichkeiten ist im globalen Kontext ein entscheidender Wettbewerbsfaktor.<\/p>\n<p>Wir, die Unterzeichnerinnen und Unterzeichner, setzen uns daf\u00fcr ein, dass diese Potenziale der digitalen Medien und Kommunikationssysteme f\u00fcr die Allgemeinheit und hier insbesondere f\u00fcr die Wissenschaft offen nutzbar bleiben und nicht vorrangig zur privatwirtschaftlichen Vermarktung von Information restriktiv reguliert werden:<\/p>\n<p>In einer digitalisierten und vernetzten Informationsgesellschaft muss der Zugang zur weltweiten Information f\u00fcr jedermann zu jeder Zeit von jedem Ort f\u00fcr Zwecke der Bildung und Wissenschaft sichergestellt werden!&#8221;<\/cite><br \/>\n<a href=\"http:\/\/www.urheberrechtsbuendnis.de\/index.html\">Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft<\/a><br \/>\n<!--more--><br \/>\nIch unterschreibe wirklich nicht gerne. Aber in diesem Fall gerne. Die &#8220;G\u00f6ttinger Erkl\u00e4rung zum Urheberrecht f\u00fcr Bildung und Wissenschaft vom 5. Juli 2004&#8221;.<br \/>\n<!--break--><br \/>\n<cite>Mit der Antwort auf die Frage &quot;Wie zug\u00e4nglich sind Wissen und Information?&quot; wird entschieden \u00fcber die Bildungs- und Entwicklungschancen jedes einzelnen B\u00fcrgers in der Informationsgesellschaft wie auch \u00fcber die Chancen k\u00fcnftiger Generationen, auf dem vorhandenen Wissen aufbauen zu k\u00f6nnen. Die im Urheberrechtsgesetz (UrhG) getroffenen gesetzlichen Regelungen haben nachhaltigen Einfluss darauf, ob sich in unserer Gesellschaft offene, vernetzte Kommunikations- und Informationsstrukturen entwickeln k\u00f6nnen. Sie entscheiden damit auch \u00fcber die Qualit\u00e4t unseres Bildungssystems, \u00fcber die Inventionsf\u00e4higkeit der Wissenschaft und die Innovationskraft der Wirtschaft. Im globalen Wettbewerb sind sie die wesentlichen Faktoren f\u00fcr eine prosperierende soziale, kulturelle und \u00f6konomische Entwicklung und damit f\u00fcr die Zukunft unserer Gesellschaft.<\/p>\n<p>Bei der Umsetzung der Richtlinie 2001\/29\/EG in das Urheberrecht hat der Gesetzgeber bisher vornehmlich die Belange der Rechteverwerter zur kommerziellen Nutzung der digitalen Medien und der Netze als zus\u00e4tzliche Vertriebswege ber\u00fccksichtigt. Im Vordergrund standen vor allem die Vermeidung von Risiken f\u00fcr die private Rechteverwertung und nicht die Nutzung der mit den neuen technischen Medien verbundenen Chancen f\u00fcr die Allgemeinheit. Dies gilt insbesondere f\u00fcr den Bereich von Bildung und Wissenschaft. Die Informationsgesellschaft bietet hier neue Potenziale der Wissensvermittlung und der Zusammenarbeit von Wissenschaftlerinnen und Wissenschaftlern. Die Nutzung dieser neuen M\u00f6glichkeiten ist im globalen Kontext ein entscheidender Wettbewerbsfaktor.<\/p>\n<p>Wir, die Unterzeichnerinnen und Unterzeichner, setzen uns daf\u00fcr ein, dass diese Potenziale der digitalen Medien und Kommunikationssysteme f\u00fcr die Allgemeinheit und hier insbesondere f\u00fcr die Wissenschaft offen nutzbar bleiben und nicht vorrangig zur privatwirtschaftlichen Vermarktung von Information restriktiv reguliert werden:<\/p>\n<p>In einer digitalisierten und vernetzten Informationsgesellschaft muss der Zugang zur weltweiten Information f\u00fcr jedermann zu jeder Zeit von jedem Ort f\u00fcr Zwecke der Bildung und Wissenschaft sichergestellt werden!&#8221;<\/cite><br \/>\n<a href=\"http:\/\/www.urheberrechtsbuendnis.de\/index.html\">Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft<\/a><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Ich unterschreibe wirklich nicht gerne. Aber in diesem Fall gerne. Die &#8220;G\u00f6ttinger Erkl\u00e4rung zum Urheberrecht f\u00fcr Bildung und Wissenschaft vom 5. Juli 2004&#8221;. Mit der Antwort auf die Frage &quot;Wie zug\u00e4nglich sind Wissen und Information?&quot; wird entschieden \u00fcber die Bildungs- und Entwicklungschancen jedes einzelnen B\u00fcrgers in der Informationsgesellschaft wie auch \u00fcber die Chancen k\u00fcnftiger Generationen, [&hellip;]<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Aktionsbuendnis%3A%20Urheberrecht%20fuer%20Bildung%20und%20Wissenschaft%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F09%2Faktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":4773,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-749","post","type-post","status-publish","format-standard","hentry","entry"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Ich unterschreibe wirklich nicht gerne. Aber in diesem Fall gerne. Die &#8220;G\u00f6ttinger Erkl\u00e4rung zum Urheberrecht f\u00fcr Bildung und Wissenschaft vom 5. Juli 2004&#8221;. Mit der Antwort auf die Frage &quot;Wie zug\u00e4nglich sind Wissen und Information?&quot; wird entschieden \u00fcber die Bildungs- und Entwicklungschancen jedes einzelnen B\u00fcrgers in der Informationsgesellschaft wie auch \u00fcber die Chancen k\u00fcnftiger Generationen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2004-09-14T18:49:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T07:49:46+00:00\" \/>\n<meta name=\"author\" content=\"huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/\"},\"author\":{\"name\":\"huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\"},\"headline\":\"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft\",\"datePublished\":\"2004-09-14T18:49:41+00:00\",\"dateModified\":\"2023-12-18T07:49:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/\"},\"wordCount\":646,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/\",\"name\":\"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"datePublished\":\"2004-09-14T18:49:41+00:00\",\"dateModified\":\"2023-12-18T07:49:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0085\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2005\\\/11\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\",\"name\":\"huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"caption\":\"huflaikhan\"},\"description\":\"Musikwissenschaftler, Ideologiekritiker seit 1964.\",\"sameAs\":[\"https:\\\/\\\/kritische-masse.de\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/huflaikhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft - Kritische Masse","og_description":"Ich unterschreibe wirklich nicht gerne. Aber in diesem Fall gerne. Die &#8220;G\u00f6ttinger Erkl\u00e4rung zum Urheberrecht f\u00fcr Bildung und Wissenschaft vom 5. Juli 2004&#8221;. Mit der Antwort auf die Frage &quot;Wie zug\u00e4nglich sind Wissen und Information?&quot; wird entschieden \u00fcber die Bildungs- und Entwicklungschancen jedes einzelnen B\u00fcrgers in der Informationsgesellschaft wie auch \u00fcber die Chancen k\u00fcnftiger Generationen, [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2004-09-14T18:49:41+00:00","article_modified_time":"2023-12-18T07:49:46+00:00","author":"huflaikhan","twitter_misc":{"Verfasst von":"huflaikhan","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/"},"author":{"name":"huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932"},"headline":"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft","datePublished":"2004-09-14T18:49:41+00:00","dateModified":"2023-12-18T07:49:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/"},"wordCount":646,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/","name":"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"datePublished":"2004-09-14T18:49:41+00:00","dateModified":"2023-12-18T07:49:46+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/aktionsbuendnis-urheberrecht-fuer-bildung-und-wissenschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"\u0085","item":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/11\/content\/"},{"@type":"ListItem","position":3,"name":"Aktionsbuendnis: Urheberrecht fuer Bildung und Wissenschaft"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932","name":"huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","caption":"huflaikhan"},"description":"Musikwissenschaftler, Ideologiekritiker seit 1964.","sameAs":["https:\/\/kritische-masse.de"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/huflaikhan\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":[],"post_class":[["post-749","post","type-post","status-publish","format-standard","hentry","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":2384,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2008\/02\/urheberrecht-aktuell\/","url_meta":{"origin":749,"position":0},"title":"Urheberrecht aktuell","author":"hufi","date":"29. Februar 2008","format":false,"excerpt":"Zeit f\u00fcr eine, mir vom Gesetzgeber aufgen\u00f6tigte ad-hoc-Meldung, nach dem Gesetz f\u00fcr die Entfaltung von Wissen und Information, das noch nicht existiert. Soeben hat das Aktionsb\u00fcndnis Urheberrecht f\u00fcr Bildung und Wissenschaft mitgeteilt, dass mit Inkrafttreten des 2. Korbes des Urheberrechts einige nicht w\u00fcnschenswerte Entwicklungen eingesetzt haben. \"Wissenschaft off-line \u2014 erste\u2026","rel":"","context":"Mit 1 Kommentar","block_context":{"text":"Mit 1 Kommentar","link":"https:\/\/www.kritische-masse.de\/logbuch\/2008\/02\/urheberrecht-aktuell\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2234,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/07\/es-geht-um-den-zweiten-korb\/","url_meta":{"origin":749,"position":1},"title":"Es geht um den &#8220;Zweiten Korb&#8221;","author":"hufi","date":"3. Juli 2007","format":false,"excerpt":"Am 5. Juli wird der Deutsche Bundestag in zweiter und dritter Lesung die Anpassung des Urheberrechtsgesetzes vermutlich beschlie\u00dfen. Von Seiten der Wissenschaft regt sich noch einmal Widerstand. Von Seiten der Unterzeichner der G\u00f6ttinger Erkl\u00e4rung wird empfohlen, das Gesetz nicht passieren zu lassen, weil es nicht bildungs- und wissenschaftsfreundlich sei. Die\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1791,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/06\/im-dunkeln\/","url_meta":{"origin":749,"position":2},"title":"Im Dunkeln \u0085","author":"huflaikhan","date":"27. Juni 2006","format":false,"excerpt":"Der Bundestag wird den Entwurf eines '\u2018Zweiten Gesetzes zur Regelung des Urheberrechts in der Informationsgesellschaft\u2019' (Korb 2) in seiner 43. Sitzung Donnerstag auf Freitag Nacht zwischen 2:35 Uhr und 3:05 Uhr beraten. [via Aktionsb\u00fcndnis \u201eUrheberrecht f\u00fcr Bildung und Wissenschaft\u201c] Ob da noch jemand wacht? Und vor allem wer?","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1425,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/09\/wahl-2005\/","url_meta":{"origin":749,"position":3},"title":"Wahl 2005","author":"huflaikhan","date":"16. September 2005","format":false,"excerpt":"Die Wahlpr\u00fcfsteine des Aktionsb\u00fcndnisses \u201eUrheberrecht f\u00fcr Bildung und Wissenschaft\u201c .","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8279,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/11\/nutzungswert-enzyklopaedie-der-kritischen-masse\/","url_meta":{"origin":749,"position":4},"title":"Nutzungswert [Enzyklop\u00e4die der Kritischen Masse]","author":"der huflaikhan","date":"15. November 2004","format":false,"excerpt":"Die heutige Pressemeldung aus dem Hause der Deutschen Phonoverb\u00e4nde mit dem Titel:\u00a0Forum der Rechteinhaber fordert angemessene pauschale Verg\u00fctungen und effektivere Regeln zur Pirateriebek\u00e4mpfung im Urheberrechtsgesetz\u00a0ist ein bisschen pikant. Die pauschalen Verg\u00fctungen auf Ger\u00e4ten und Leermedien befinden sich auf dem Stand von 1985. Die Bundesregierung hat bereits in zwei Verg\u00fctungsberichten festgestellt,\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8342,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2008\/06\/neues-aus-dem-grand-tokio-hotel-abgrund-urheberrecht-als-musikalische-warenkunde\/","url_meta":{"origin":749,"position":5},"title":"Neues aus dem Grand-Tokio-Hotel-Abgrund \u2013 Urheberrecht als musikalische Warenkunde","author":"der huflaikhan","date":"22. Juni 2008","format":false,"excerpt":"Das Gezerre um die angemessene Verg\u00fctung von urheberrechtlichen Leistungen will kein Ende nehmen. Seit einigen Jahren werden sogenannte K\u00f6rbe zum Urheberrecht gepackt. Teilweise sind Erg\u00e4nzungen und Korrekturen n\u00f6tig, weil es Auflagen der europ\u00e4ischen Kommission gibt, teilweise werden diese Anforderungen genutzt, um weitergehende neue Anspr\u00fcche zu begr\u00fcnden. Dieses tat zuletzt ein\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"20050207-ratung","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/05\/20050207-ratung.jpg?fit=500%2C291&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=749"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/749\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}