{"id":767,"date":"2004-09-21T12:54:35","date_gmt":"2004-09-21T11:54:35","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/"},"modified":"2023-12-18T08:49:45","modified_gmt":"2023-12-18T07:49:45","slug":"dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/","title":{"rendered":"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt"},"content":{"rendered":"<p>Was f\u00fcr eine Nachricht! Dieter Gorny tritt die Nachfolge Jens Michows an, der sich vor kurzem aus dem gesch\u00e4ftf\u00fchrenden Pr\u00e4sidium des Deutschen Musikrates verabschiedet hatte. Das <a href=\"http:\/\/www.nmz.de\/kiz\/modules.php?op=modload&#038;name=News&#038;file=article&#038;sid=7985\">bedauerte der Pr\u00e4sident des Deutschen Musikrats<\/a>, Martin Maria Kr\u00fcger, zwar sehr, Michow schien aber doch sehr entt\u00e4uscht, wie er dem MusikMarkt kundtat.<br \/>\n<cite>&#8222;Wenn man nichts mehr bewegen kann, sollte man aufh\u00f6ren. Ich bin nach reiflicher \u00dcberlegung zu der \u00dcberzeugung gelangt, dass sich meine Vorstellung von Verbands- und vor allem Teamarbeit nicht l\u00e4nger mit der Arbeitsweise meiner engsten Pr\u00e4sidiumskollegen vereinbaren l\u00e4sst. &#8230; Leider ist es dem Pr\u00e4sidium bis heute nicht gelungen, das versprochene DMR-Engagement im Bereich der Rock- und Popmusik auch nur ansatzweise zu realisieren, schlie\u00dflich war dies unser zentrales Anliegen und Wahlversprechen&#8220;, zitiert ihn der <a href=\"http:\/\/www.musikmarkt.de\/content\/news\/news_2.php3?bid=10519&#038;th=10519\" target=\"_blank\" rel=\"noopener\">Musikmarkt<\/a>.<\/cite><br \/>\nAlso ist nat\u00fcrlich Platz da f\u00fcr einen neuen Pr\u00e4sidiumskollegen, dessen Vorstellung von Verbands- und Teamarbeit besser mit den Pr\u00e4sidiumskollegen zu vereinbaren ist. Und den fand man dann auch: Dieter Gorny &#8212; das Urgestein des Deutschen Musikrates? Und so kommt der Deutsche Musikrat aus den Schlagzeilen nicht heraus. <\/p>\n<p>Wir erinnern uns: Vor vier Jahren sollten die neuen Pr\u00e4sidiumsmitglieder gew\u00e4hlt werden. Die neue musikzeitung stellte den Kandidaten ein paar kleine Fragen, wie zum Beispiel diese (+ Antwort Gorny):<br \/>\n<cite><b>Ihre Beweggr\u00fcnde, sich zur Wahl des Pr\u00e4sidiums des Deutschen Musikrates zu stellen?<\/b><br \/>\nMusik und Kultur brauchen Engagement. (<a href=\"http:\/\/www.nmz.de\/nmz\/nmz2000\/nmz11\/kupo-kandidaten-gorny.shtml\">Quelle<\/a>)<\/cite><br \/>\nKnackig, nicht wahr. Sein nachhaltiges Interesse an einer Wahl zeigte er bereits damals durch Abwesenheit w\u00e4hrend der damaligen Mitgliederversammlung. Die damalige Generalsekret\u00e4rin Marlene Wartenberg \u00e4u\u00dferte sich dazu wie folgt:<br \/>\n<cite>Aus politischen Gr\u00fcnen bedaure ich, dass die Mitglieder des Deutschen Musikrates durch ihre Wahl in der Generalversammlung dieses Signal gesetzt haben. (<a href=\"http:\/\/www.nmz.de\/nmz\/nmz2000\/nmz12\/cluster-musikrat.shtml\">Quelle<\/a>)<\/cite><br \/>\nAlle lieben Dieter Gorny, nur nicht die alle Mitglieder des Deutschen Musikrates, sonst h\u00e4tten sie ihn ja gew\u00e4hlt. &#8222;D\u00e4mlicher Souver\u00e4n&#8220; war der nmz-Cluster \u00fcberschrieben. Hatten wir sowas nicht vor wenigen Tagen auch? Nein, das w\u00e4re ungerecht, schlie\u00dflich ist Gorny jetzt demokratisch gew\u00e4hlt worden, n\u00e4mlich vom sog. erweiterten Pr\u00e4sidium des Deutschen Musikrates.<\/p>\n<p>Mit etwas Verwunderung ist allerdings zur Kenntnis zu nehmen, dass ein Kommentar im Kulturinformationszentrum des Deutschen Kulturrates und der ConBrio Verlagsgesellschaft im Laufe des heutigen Tages gel\u00f6scht worden ist. Warum eigentlich? Obwohl: Eigentlich ist das ganz klar.<br \/>\n<!--break--><br \/>\n<cite>Sondershausen, (nmz). Als <b>Nachfolger f\u00fcr den resignierten Jens Michow<\/b> hat das Pr\u00e4sidium des Deutschen Musikrates bei seiner Sitzung in Sondershausen den <b>ehemaligen Musikp\u00e4dagogen und ehemaligen VIVA-Boss Dieter Gorny<\/b> f\u00fcr zun\u00e4chst ein Jahr in den F\u00fcnfer-Kreis der Vereins-Gesch\u00e4ftsf\u00fchrung berufen. Nicht gerade ein zukunftsweisendes Signal. Michow ist mittlerweile mit \u0084seinem\u0093 Verband, dem IDKV &#8211; einer Veranstalter-Vereinigung offensichtlich beleidigt aus dem Musikrat ausgetreten.<\/p>\n<p>In einer nach zuverl\u00e4ssigen Angaben hei\u00df umk\u00e4mpften, sehr knappen Entscheidung fiel die Wahl auf den wirtschaftlich angeblich kompetenteren Kandidaten. Betrachtet man Gornys j\u00fcngste Karriere-Knicke, k\u00f6nnte man auch von einer Verlegenheitsl\u00f6sung sprechen. Klassik-Komm. versenkt, Pop-Komm grade mal an Berlin verscheuert, VIVA an den Konkurrenten MTV verloren. Auch im <a href=\"http:\/\/www.musikrat.de\" title=\"Deutscher Musikrat | Zum deutschen Musikrat\" target=\"_blank\" rel=\"noopener\">Musikrat<\/a> selbst hat Gorny in den vergangenen Jahren kaum durch Aktivit\u00e4t gegl\u00e4nzt &#8212; w\u00e4hrend der Konkurs-Krise allenfalls durch Abwesenheit. Ein Fall von welkem Name-Dropping? Offensichtlich wollte man aber nach der Einbeziehung Hans B\u00e4\u00dflers in die \u0084F\u00fcnferbande\u0093, wie das gesch\u00e4ftsf\u00fchrende Pr\u00e4sidium von Insidern mittlerweile z\u00e4rtlich-sp\u00f6ttisch genannt wird, eine st\u00e4rkere Einflu\u00dfnahme professioneller P\u00e4dagogen verhindern.<\/p>\n<p>Der Vorgang macht deutlich, dass die als Schaffung einer \u0084Task-Force\u0093 in der Notsituation der Insolvenz gedachte, seinerzeit brauchbare Zweiteilung des Pr\u00e4sidiums als dauerhafte L\u00f6sung wenig taugt. Zumal einige der gesch\u00e4ftsf\u00fchrenden Pr\u00e4sidialen ihr Amt mittlerweile sehr stark an ihre reale oder vermeintliche Pers\u00f6nlichkeit gekn\u00fcpft sehen. Schon bei der n\u00e4chsten Generalversammlung Ende Oktober sollte der Souver\u00e4n, also die Mitgliedsverb\u00e4nde, sehr ernsthaft \u00fcber eine Satzungs\u00e4nderung nachdenken. Sinnvoller als ein Zweiklassen-Vorstand mit f\u00fcnf Oberh\u00e4uptern und zw\u00f6lf bis 14 Beisprechern scheint doch ein auf neun bis elf K\u00f6pfe verkleinertes Gesamtpr\u00e4sidium, in dem sich die weitgef\u00e4cherte Kompetenz der Mitgliedsverb\u00e4nde angemessen widerspiegelt. <br \/>\n<i>Quelle: Autor: Webwatch &#8212; Wurde mittlerweile im Kulturinformationszentrum gel\u00f6scht.<\/i> <\/cite><\/p>\n<p><b>Update:<\/b> Und au\u00dferdem, Gorny ist mal so reingerutscht, die Satzung des Musikrates sieht es so vor: <br \/>\n<cite>&#8222;Scheidet ein Mitglied des Gesch\u00e4ftsf\u00fchrenden Pr\u00e4sidiums vor Ablauf seines Mandats aus, kann das Pr\u00e4sidium ein Ersatzmitglied f\u00fcr die restliche Amtszeit bestellen.&#8220;<\/cite><br \/>\nIm Oktober, w\u00e4hrend der n\u00e4chsten Mitgliederversammlung des Deutschen Musikrates, sind die Mitglieder wieder der Souver\u00e4n: <br \/>\n<cite>&#8220;Die Mitgliederversammlung hat folgende Aufgaben:<br \/>\n   a. Wahl des Pr\u00e4sidenten auf die Dauer von vier Jahren<br \/>\n   b. Wahl der Mitglieder des Gesch\u00e4ftsf\u00fchrenden Pr\u00e4sidiums auf die Dauer von vier Jahren<br \/>\n   c. Wahl der weiteren Mitglieder des Pr\u00e4sidiums auf die Dauer von vier Jahren<\/cite><br \/>\nLiebe Mitglieder des Deutschen Musikrates, nehmt eure Sache ernst und w\u00e4hlt, wen <b>ihr<\/b> wollt!<br \/>\n<!--more--><br \/>\nWas f\u00fcr eine Nachricht! Dieter Gorny tritt die Nachfolge Jens Michows an, der sich vor kurzem aus dem gesch\u00e4ftf\u00fchrenden Pr\u00e4sidium des Deutschen Musikrates verabschiedet hatte. Das <a href=\"http:\/\/www.nmz.de\/kiz\/modules.php?op=modload&#038;name=News&#038;file=article&#038;sid=7985\">bedauerte der Pr\u00e4sident des Deutschen Musikrats<\/a>, Martin Maria Kr\u00fcger, zwar sehr, Michow schien aber doch sehr entt\u00e4uscht, wie er dem MusikMarkt kundtat.<br \/>\n<cite>&#8222;Wenn man nichts mehr bewegen kann, sollte man aufh\u00f6ren. Ich bin nach reiflicher \u00dcberlegung zu der \u00dcberzeugung gelangt, dass sich meine Vorstellung von Verbands- und vor allem Teamarbeit nicht l\u00e4nger mit der Arbeitsweise meiner engsten Pr\u00e4sidiumskollegen vereinbaren l\u00e4sst. &#8230; Leider ist es dem Pr\u00e4sidium bis heute nicht gelungen, das versprochene DMR-Engagement im Bereich der Rock- und Popmusik auch nur ansatzweise zu realisieren, schlie\u00dflich war dies unser zentrales Anliegen und Wahlversprechen&#8220;, zitiert ihn der <a href=\"http:\/\/www.musikmarkt.de\/content\/news\/news_2.php3?bid=10519&#038;th=10519\" target=\"_blank\" rel=\"noopener\">Musikmarkt<\/a>.<\/cite><br \/>\nAlso ist nat\u00fcrlich Platz da f\u00fcr einen neuen Pr\u00e4sidiumskollegen, dessen Vorstellung von Verbands- und Teamarbeit besser mit den Pr\u00e4sidiumskollegen zu vereinbaren ist. Und den fand man dann auch: Dieter Gorny &#8212; das Urgestein des Deutschen Musikrates? Und so kommt der Deutsche Musikrat aus den Schlagzeilen nicht heraus. <\/p>\n<p>Wir erinnern uns: Vor vier Jahren sollten die neuen Pr\u00e4sidiumsmitglieder gew\u00e4hlt werden. Die neue musikzeitung stellte den Kandidaten ein paar kleine Fragen, wie zum Beispiel diese (+ Antwort Gorny):<br \/>\n<cite><b>Ihre Beweggr\u00fcnde, sich zur Wahl des Pr\u00e4sidiums des Deutschen Musikrates zu stellen?<\/b><br \/>\nMusik und Kultur brauchen Engagement. (<a href=\"http:\/\/www.nmz.de\/nmz\/nmz2000\/nmz11\/kupo-kandidaten-gorny.shtml\">Quelle<\/a>)<\/cite><br \/>\nKnackig, nicht wahr. Sein nachhaltiges Interesse an einer Wahl zeigte er bereits damals durch Abwesenheit w\u00e4hrend der damaligen Mitgliederversammlung. Die damalige Generalsekret\u00e4rin Marlene Wartenberg \u00e4u\u00dferte sich dazu wie folgt:<br \/>\n<cite>Aus politischen Gr\u00fcnen bedaure ich, dass die Mitglieder des Deutschen Musikrates durch ihre Wahl in der Generalversammlung dieses Signal gesetzt haben. (<a href=\"http:\/\/www.nmz.de\/nmz\/nmz2000\/nmz12\/cluster-musikrat.shtml\">Quelle<\/a>)<\/cite><br \/>\nAlle lieben Dieter Gorny, nur nicht die alle Mitglieder des Deutschen Musikrates, sonst h\u00e4tten sie ihn ja gew\u00e4hlt. &#8222;D\u00e4mlicher Souver\u00e4n&#8220; war der nmz-Cluster \u00fcberschrieben. Hatten wir sowas nicht vor wenigen Tagen auch? Nein, das w\u00e4re ungerecht, schlie\u00dflich ist Gorny jetzt demokratisch gew\u00e4hlt worden, n\u00e4mlich vom sog. erweiterten Pr\u00e4sidium des Deutschen Musikrates.<\/p>\n<p>Mit etwas Verwunderung ist allerdings zur Kenntnis zu nehmen, dass ein Kommentar im Kulturinformationszentrum des Deutschen Kulturrates und der ConBrio Verlagsgesellschaft im Laufe des heutigen Tages gel\u00f6scht worden ist. Warum eigentlich? Obwohl: Eigentlich ist das ganz klar.<br \/>\n<!--break--><br \/>\n<cite>Sondershausen, (nmz). Als <b>Nachfolger f\u00fcr den resignierten Jens Michow<\/b> hat das Pr\u00e4sidium des Deutschen Musikrates bei seiner Sitzung in Sondershausen den <b>ehemaligen Musikp\u00e4dagogen und ehemaligen VIVA-Boss Dieter Gorny<\/b> f\u00fcr zun\u00e4chst ein Jahr in den F\u00fcnfer-Kreis der Vereins-Gesch\u00e4ftsf\u00fchrung berufen. Nicht gerade ein zukunftsweisendes Signal. Michow ist mittlerweile mit \u0084seinem\u0093 Verband, dem IDKV &#8211; einer Veranstalter-Vereinigung offensichtlich beleidigt aus dem Musikrat ausgetreten.<\/p>\n<p>In einer nach zuverl\u00e4ssigen Angaben hei\u00df umk\u00e4mpften, sehr knappen Entscheidung fiel die Wahl auf den wirtschaftlich angeblich kompetenteren Kandidaten. Betrachtet man Gornys j\u00fcngste Karriere-Knicke, k\u00f6nnte man auch von einer Verlegenheitsl\u00f6sung sprechen. Klassik-Komm. versenkt, Pop-Komm grade mal an Berlin verscheuert, VIVA an den Konkurrenten MTV verloren. Auch im <a href=\"http:\/\/www.musikrat.de\" title=\"Deutscher Musikrat | Zum deutschen Musikrat\" target=\"_blank\" rel=\"noopener\">Musikrat<\/a> selbst hat Gorny in den vergangenen Jahren kaum durch Aktivit\u00e4t gegl\u00e4nzt &#8212; w\u00e4hrend der Konkurs-Krise allenfalls durch Abwesenheit. Ein Fall von welkem Name-Dropping? Offensichtlich wollte man aber nach der Einbeziehung Hans B\u00e4\u00dflers in die \u0084F\u00fcnferbande\u0093, wie das gesch\u00e4ftsf\u00fchrende Pr\u00e4sidium von Insidern mittlerweile z\u00e4rtlich-sp\u00f6ttisch genannt wird, eine st\u00e4rkere Einflu\u00dfnahme professioneller P\u00e4dagogen verhindern.<\/p>\n<p>Der Vorgang macht deutlich, dass die als Schaffung einer \u0084Task-Force\u0093 in der Notsituation der Insolvenz gedachte, seinerzeit brauchbare Zweiteilung des Pr\u00e4sidiums als dauerhafte L\u00f6sung wenig taugt. Zumal einige der gesch\u00e4ftsf\u00fchrenden Pr\u00e4sidialen ihr Amt mittlerweile sehr stark an ihre reale oder vermeintliche Pers\u00f6nlichkeit gekn\u00fcpft sehen. Schon bei der n\u00e4chsten Generalversammlung Ende Oktober sollte der Souver\u00e4n, also die Mitgliedsverb\u00e4nde, sehr ernsthaft \u00fcber eine Satzungs\u00e4nderung nachdenken. Sinnvoller als ein Zweiklassen-Vorstand mit f\u00fcnf Oberh\u00e4uptern und zw\u00f6lf bis 14 Beisprechern scheint doch ein auf neun bis elf K\u00f6pfe verkleinertes Gesamtpr\u00e4sidium, in dem sich die weitgef\u00e4cherte Kompetenz der Mitgliedsverb\u00e4nde angemessen widerspiegelt. <br \/>\n<i>Quelle: Autor: Webwatch &#8212; Wurde mittlerweile im Kulturinformationszentrum gel\u00f6scht.<\/i> <\/cite><\/p>\n<p><b>Update:<\/b> Und au\u00dferdem, Gorny ist mal so reingerutscht, die Satzung des Musikrates sieht es so vor: <br \/>\n<cite>&#8222;Scheidet ein Mitglied des Gesch\u00e4ftsf\u00fchrenden Pr\u00e4sidiums vor Ablauf seines Mandats aus, kann das Pr\u00e4sidium ein Ersatzmitglied f\u00fcr die restliche Amtszeit bestellen.&#8220;<\/cite><br \/>\nIm Oktober, w\u00e4hrend der n\u00e4chsten Mitgliederversammlung des Deutschen Musikrates, sind die Mitglieder wieder der Souver\u00e4n: <br \/>\n<cite>&#8220;Die Mitgliederversammlung hat folgende Aufgaben:<br \/>\n   a. Wahl des Pr\u00e4sidenten auf die Dauer von vier Jahren<br \/>\n   b. Wahl der Mitglieder des Gesch\u00e4ftsf\u00fchrenden Pr\u00e4sidiums auf die Dauer von vier Jahren<br \/>\n   c. Wahl der weiteren Mitglieder des Pr\u00e4sidiums auf die Dauer von vier Jahren<\/cite><br \/>\nLiebe Mitglieder des Deutschen Musikrates, nehmt eure Sache ernst und w\u00e4hlt, wen <b>ihr<\/b> wollt!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was f\u00fcr eine Nachricht! Dieter Gorny tritt die Nachfolge Jens Michows an, der sich vor kurzem aus dem gesch\u00e4ftf\u00fchrenden Pr\u00e4sidium des Deutschen Musikrates verabschiedet hatte. Das bedauerte der Pr\u00e4sident des Deutschen Musikrats, Martin Maria Kr\u00fcger, zwar sehr, Michow schien aber doch sehr entt\u00e4uscht, wie er dem MusikMarkt kundtat. &#8222;Wenn man nichts mehr bewegen kann, sollte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":10945,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-767","post","type-post","status-publish","format-standard","hentry","entry"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Was f\u00fcr eine Nachricht! Dieter Gorny tritt die Nachfolge Jens Michows an, der sich vor kurzem aus dem gesch\u00e4ftf\u00fchrenden Pr\u00e4sidium des Deutschen Musikrates verabschiedet hatte. Das bedauerte der Pr\u00e4sident des Deutschen Musikrats, Martin Maria Kr\u00fcger, zwar sehr, Michow schien aber doch sehr entt\u00e4uscht, wie er dem MusikMarkt kundtat. &#8222;Wenn man nichts mehr bewegen kann, sollte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2004-09-21T11:54:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T07:49:45+00:00\" \/>\n<meta name=\"author\" content=\"huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/\"},\"author\":{\"name\":\"huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\"},\"headline\":\"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt\",\"datePublished\":\"2004-09-21T11:54:35+00:00\",\"dateModified\":\"2023-12-18T07:49:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/\"},\"wordCount\":1638,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/\",\"name\":\"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"datePublished\":\"2004-09-21T11:54:35+00:00\",\"dateModified\":\"2023-12-18T07:49:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/09\\\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0085\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2005\\\/11\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\",\"name\":\"huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"caption\":\"huflaikhan\"},\"description\":\"Musikwissenschaftler, Ideologiekritiker seit 1964.\",\"sameAs\":[\"https:\\\/\\\/kritische-masse.de\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/huflaikhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/","og_locale":"de_DE","og_type":"article","og_title":"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt - Kritische Masse","og_description":"Was f\u00fcr eine Nachricht! Dieter Gorny tritt die Nachfolge Jens Michows an, der sich vor kurzem aus dem gesch\u00e4ftf\u00fchrenden Pr\u00e4sidium des Deutschen Musikrates verabschiedet hatte. Das bedauerte der Pr\u00e4sident des Deutschen Musikrats, Martin Maria Kr\u00fcger, zwar sehr, Michow schien aber doch sehr entt\u00e4uscht, wie er dem MusikMarkt kundtat. &#8222;Wenn man nichts mehr bewegen kann, sollte [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2004-09-21T11:54:35+00:00","article_modified_time":"2023-12-18T07:49:45+00:00","author":"huflaikhan","twitter_misc":{"Verfasst von":"huflaikhan","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/"},"author":{"name":"huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932"},"headline":"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt","datePublished":"2004-09-21T11:54:35+00:00","dateModified":"2023-12-18T07:49:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/"},"wordCount":1638,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/","name":"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"datePublished":"2004-09-21T11:54:35+00:00","dateModified":"2023-12-18T07:49:45+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/09\/dieter-gorny-ins-praesidium-des-deutschen-musikrates-gewaehlt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"\u0085","item":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/11\/content\/"},{"@type":"ListItem","position":3,"name":"Dieter Gorny ins Pr\u00e4sidium des Deutschen Musikrates gew\u00e4hlt"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932","name":"huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","caption":"huflaikhan"},"description":"Musikwissenschaftler, Ideologiekritiker seit 1964.","sameAs":["https:\/\/kritische-masse.de"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/huflaikhan\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":[],"post_class":[["post-767","post","type-post","status-publish","format-standard","hentry","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":8383,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/06\/preisverfallen-stalin-orden-fuer-die-musikraete\/","url_meta":{"origin":767,"position":0},"title":"Preisverfallen \u2013 Stalin-Orden f\u00fcr die Musikr\u00e4te","author":"der huflaikhan","date":"7. Juni 2012","format":false,"excerpt":"Sie sind dem Preis verfallen. Das Bundesjazzorchester erh\u00e4lt den ECHO Jazz, Jugend musiziert erhielt den ECHO Klassik. Auf beiden Websites prangt jetzt ein h\u00fcbsches (?) Logo mit dem Titel: Deutscher Musikpreis. Deutscher Musikpreis, das klingt aus den Ohren der Musikindustrie etwas anders, eher nach Stalin-Orden. Den ECHO vergibt die Kulturorganisation\u2026","rel":"","context":"In &quot;die Musik&quot;","block_context":{"text":"die Musik","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/diemusik\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3059,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/06\/preisverfallen-stalin-orden-f-r-die-musikr-te\/","url_meta":{"origin":767,"position":1},"title":"Preisverfallen &#8211; Stalin-Orden f\u00fcr die Musikr\u00e4te","author":"huflaikhan","date":"6. Juni 2012","format":false,"excerpt":"Sie sind dem Preis verfallen. Das Bundesjazzorchester erh\u00e4lt den ECHO Jazz, Jugend musiziert erhielt den ECHO Klassik. Auf beiden Websites prangt jetzt ein h\u00fcbsches (?) Logo mit dem Titel: Deutscher Musikpreis. Deutscher Musikpreis, das klingt aus den Ohren der Musikindustrie etwas anders, eher nach Stalin-Orden.\u00a0 Den ECHO vergibt die Kulturorganisation\u2026","rel":"","context":"In \"BuJazzO\"","block_context":{"text":"BuJazzO","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/bujazzo\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":272,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2003\/11\/musikrat-im-kluengelfieber-aus-ueberzeugung-alt-teil-ii\/","url_meta":{"origin":767,"position":2},"title":"Musikrat im Kl\u00fcngelfieber &#8211; Aus \u00dcberzeugung alt (Teil II)","author":"huflaikhan","date":"11. November 2003","format":false,"excerpt":"Das muss man sich mal auf der Zunge zergehen lassen. Im Gespr\u00e4ch mit der Pressesprecherin [Pressereferentin] des Deutschen Musikrates (Susanne Flie\u00df) \u00e4u\u00dfert der Pr\u00e4sident dieses Unternehmens: Es [das alte Musikforum] war sehr niveauvoll, aber wer liest heute eine Zeitschrift, bestehend aus einer Ansammlung kluger Artikel, wirklich von vorne bis hinten\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":271,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2003\/11\/musikrat-im-kluengelfieber-aus-ueberzeugung-alt-teil-i\/","url_meta":{"origin":767,"position":3},"title":"Musikrat im Kl\u00fcngelfieber &#8211; Aus \u00dcberzeugung alt (Teil I)","author":"huflaikhan","date":"11. November 2003","format":false,"excerpt":"Einen l\u00e4sst der Eindruck nicht los, dass der neue Musikrat so weiter macht, wo der alte unter Thomas Rietschel gerade begann aufzur\u00e4umen; also davor. Das deutsche Musikleben scheint verfilzt und zugen\u00e4ht. Nach DMR intern nun das MusikFORUM, welches wie das alte im Schott Musikverlag in Mainz erscheint. Und man dankt\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":225,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2003\/08\/deutscher-musikrat-schmankerl\/","url_meta":{"origin":767,"position":4},"title":"Deutscher Musikrat \u2013 Schmankerl","author":"huflaikhan","date":"19. August 2003","format":false,"excerpt":"Nach der schwierigen Lage des Deutschen Musikrates wegen der Einleitung eines vorl\u00e4ufigen Insolvenzverfahrens, die neue musikzeitung berichtete ausf\u00fchrlich, zeigen sich die Neuerungen in ersten Ans\u00e4tzen. Der Deutsche Musikrat will mehr Flagge zeigen und die Medienpr\u00e4senz steigern. So gibt der DMR [Deutsche Musikrat] seit kurzem eine neue Zeitschrift heraus, die sich\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11277,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2025\/08\/kulturstaatsministerin-wolfram-weimer-will-genderungerechte-sprache-durchsetzen\/","url_meta":{"origin":767,"position":5},"title":"Kulturstaatsministerin Wolfram Weimer will genderungerechte Sprache durchsetzen","author":"der huflaikhan","date":"8. August 2025","format":false,"excerpt":"Die dpa meldet aus dem Hause Weimer (BKM): \u201eWeimer: Wer \u00f6ffentliches Geld erh\u00e4lt, soll nicht gendern\u201c \u2013 nur er selbst d\u00fcrfe das, in dem er gendergerechte Sprache untersage. Dieser Oberpopanz ist jetzt Kulturstaatsminister. Warum? F\u00fcr Vernunft steht er nicht, f\u00fcr Kultur steht er nicht, f\u00fcr Medien- und Kulturg\u00e4ngelung steht er\u2026","rel":"","context":"In &quot;Amt f\u00fcr Vermassungsschutz&quot;","block_context":{"text":"Amt f\u00fcr Vermassungsschutz","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/vermassungsschutz\/"},"img":{"alt_text":"create a highly detailed high resolution featured image for a blog","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/08\/create-a-highly-detailed-high-resolution-featured-image-for-a-blog.png?fit=1024%2C768&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/08\/create-a-highly-detailed-high-resolution-featured-image-for-a-blog.png?fit=1024%2C768&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/08\/create-a-highly-detailed-high-resolution-featured-image-for-a-blog.png?fit=1024%2C768&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2025\/08\/create-a-highly-detailed-high-resolution-featured-image-for-a-blog.png?fit=1024%2C768&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=767"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/767\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}