{"id":8326,"date":"2006-05-30T17:07:22","date_gmt":"2006-05-30T15:07:22","guid":{"rendered":"https:\/\/musikunrat.de\/?p=1008"},"modified":"2006-05-30T17:07:22","modified_gmt":"2006-05-30T15:07:22","slug":"versteigerung-von-musiknutzungsrechten-2","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/","title":{"rendered":"Versteigerung von Musiknutzungsrechten"},"content":{"rendered":"<p>Heute in der Mailpost. Da versteigert einer einen Popsong mit interessanten Nebenaspekten.<\/p>\n<blockquote><p>Am Dienstag, den 30.Mai, 14 Uhr MESZ, beginnt auf E-Bay Deutschland die weltweit erste Versteigerung von Nutzungsrechten eines Musiktitels. Der H\u00f6chstbietende erwirbt die Rechte zur deutschlandweiten Vermarktung des Titels \u00fcber s\u00e4mtliche Vertriebskan\u00e4le &#8211; CD, Internet, Mobiltelefone, Klingelt\u00f6ne, Film und Fernsehen, Werbung &#8211; f\u00fcr einen Zeitraum von 5 Jahren.Der Verwerter hat die M\u00f6glichkeit, den bereits produzierten Titel zu vermarkten oder ihn neu aufzunehmen. Er darf dabei auch den Text ver\u00e4ndern oder \u00fcbersetzen. Da der Autor keine Rechte an die GEMA abgetreten hat, gehen alle Brutto-Einnahmen, die der Titel generiert, f\u00fcr den genannten Zeitraum an den Verwerter. Er hat damit auch das Recht, Cover-Versionen zu lizensieren. Alle Abmachungen sind detailliert in einem Vertrag geregelt, der \u00fcber die unten genannte Kontaktadresse angefragt werden kann.<\/p>\n<p>Die Idee, Verwertungsrechte f\u00fcr einen Pauschalbetrag zeitlich begrenzt zu \u00fcbertragen, k\u00f6nnte ein Zukunftmodell f\u00fcr die Beziehung zwischen unabh\u00e4ngigen Autoren und Songwritern einerseits und Musik-Vermarktungsfirmen oder Content-Anbietern anderseits darstellen.<\/p>\n<p>Links<br \/>\n&#8211; Eine H\u00f6rprobe des Titels findet sich unter <a href=\"http:\/\/www.myspace.com\/lusiol\" target=\"_BLANK\" rel=\"noopener\">http:\/\/www.myspace.com\/lusiol<\/a><br \/>\n&#8211; Die E-Bay Auktion findet sich unter <a href=\"http:\/\/www.ebay.de\">http:\/\/www.ebay.de<\/a>. Artikelnummer: 4887358142<br \/>\n&#8211; F\u00fcr interessierte Bieter steht die folgende Kontaktm\u00f6glichkeit zur Verf\u00fcgung: pocke.bieter (at) gmail.com<\/p>\n<p>Presse-Information<br \/>\nMatthias Jung<br \/>\nMougins, Frankreich<br \/>\nxxxx (at) gmail.com<\/p><\/blockquote>\n<p>Das ist ganz erstaunlich. Das Startgebot liegt \u00fcbrigens bei 10.000 Euro, Sofortkaufen kann man f\u00fcr 100.000 Euro. \u201eDie Pocke ist drin\u201c ist so etwas wie ein Fussballsong. Keine besonders exklusive Musik, keine bedeutende Abweichung vom Schema, eher Mainstream. Aber alles ist eben fertig. Den hinter der Auktion liegenden Nutzungsvertrag habe ich nur \u00fcberflogen, das k\u00f6nnen Rechtsanw\u00e4lte besser beurteilen.<\/p>\n<p>Was nun doch so erstaunlich ist an dieser Geschichte: Ein Komponist\/Texter \u00fcbernimmt jenseits von der [GEMA] seine Rechte hier wahr. Die Sache ist nicht frei, die Sache ist nicht [Creative Commons], die Sache ist nicht billig (bestenfalls g\u00fcnstig). Wer also sollte mitbieten? Bestenfalls jemand, der das n\u00f6tige Geld hat und das Potential dieses Songs sieht (sofern vorhanden). Oder jemand B\u00f6ses, der dies auch sieht, aber will, dass dieser Song die n\u00e4chsten f\u00fcnf Jahre nicht genutzt wird.<\/p>\n<p>Und dieser Vorgang ist auch interessant, weil er offen zu erkennen gibt, was so ein St\u00fcck Wert sein soll \u2014 f\u00fcr f\u00fcnf Jahre wenigstens. Mich hat das Startgebot zun\u00e4chst \u00fcberrascht, dann aber z\u00e4hlt man 1 und 1 zusammen. Komposition, Arrangement, Aufnahme \u2014 alles in Studioqualit\u00e4t (glaub ich). Da schlagen die Kosten dann doch zu, so dass die Grundkosten (plus k\u00fcnstlerisches Honorar) mindestens drin sind.<\/p>\n<p>Ob das Schule machen wird? Muss ich mal nachverfolgen.<\/p>\n<p>Nachtrag: Standort des Titels: Mougins, Provence-Alpes-C\u00f4te d&#8217;Azur, Frankreich &#8211; keine schlechte Wahl. Und der Song ist angeblich neu. Lustiger w\u00e4rs, er w\u00e4re ein Plagiat. Aber dieser Vorwurf k\u00f6nnte nat\u00fcrlich kommen, berechtigter- oder unberechtigter Weise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute in der Mailpost. Da versteigert einer einen Popsong mit interessanten Nebenaspekten. Am Dienstag, den 30.Mai, 14 Uhr MESZ, beginnt auf E-Bay Deutschland die weltweit erste Versteigerung von Nutzungsrechten eines Musiktitels. Der H\u00f6chstbietende erwirbt die Rechte zur deutschlandweiten Vermarktung des Titels \u00fcber s\u00e4mtliche Vertriebskan\u00e4le &#8211; CD, Internet, Mobiltelefone, Klingelt\u00f6ne, Film und Fernsehen, Werbung &#8211; f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"standard","_metis_text_length":3211,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"#Versteigerung von #Musiknutzungsrechten [2006]","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2673,2652],"tags":[1889,1981,3045,2670,3046],"class_list":["post-8326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-urheberrecht","category-diemusik","tag-copyright","tag-ebay","tag-nutzungsrechte","tag-urheberrecht","tag-versteigerung","entry","has-media"],"desktop_mode_lock":null,"desktop_mode_contributors":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Versteigerung von Musiknutzungsrechten - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Versteigerung von Musiknutzungsrechten - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Heute in der Mailpost. Da versteigert einer einen Popsong mit interessanten Nebenaspekten. Am Dienstag, den 30.Mai, 14 Uhr MESZ, beginnt auf E-Bay Deutschland die weltweit erste Versteigerung von Nutzungsrechten eines Musiktitels. Der H\u00f6chstbietende erwirbt die Rechte zur deutschlandweiten Vermarktung des Titels \u00fcber s\u00e4mtliche Vertriebskan\u00e4le &#8211; CD, Internet, Mobiltelefone, Klingelt\u00f6ne, Film und Fernsehen, Werbung &#8211; f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2006-05-30T15:07:22+00:00\" \/>\n<meta name=\"author\" content=\"der huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"der huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/\"},\"author\":{\"name\":\"der huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"headline\":\"Versteigerung von Musiknutzungsrechten\",\"datePublished\":\"2006-05-30T15:07:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/\"},\"wordCount\":486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Copyright\",\"ebay\",\"Nutzungsrechte\",\"Urheberrecht\",\"Versteigerung\"],\"articleSection\":[\"das Urheberrecht\",\"die Musik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/\",\"name\":\"Versteigerung von Musiknutzungsrechten - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2006-05-30T15:07:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2006\\\/05\\\/versteigerung-von-musiknutzungsrechten-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Versteigerung von Musiknutzungsrechten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/martin_d1juqiu5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Versteigerung von Musiknutzungsrechten - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/","og_locale":"de_DE","og_type":"article","og_title":"Versteigerung von Musiknutzungsrechten - Kritische Masse","og_description":"Heute in der Mailpost. Da versteigert einer einen Popsong mit interessanten Nebenaspekten. Am Dienstag, den 30.Mai, 14 Uhr MESZ, beginnt auf E-Bay Deutschland die weltweit erste Versteigerung von Nutzungsrechten eines Musiktitels. Der H\u00f6chstbietende erwirbt die Rechte zur deutschlandweiten Vermarktung des Titels \u00fcber s\u00e4mtliche Vertriebskan\u00e4le &#8211; CD, Internet, Mobiltelefone, Klingelt\u00f6ne, Film und Fernsehen, Werbung &#8211; f\u00fcr [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_author":"https:\/\/www.facebook.com\/hufner","article_published_time":"2006-05-30T15:07:22+00:00","author":"der huflaikhan","twitter_misc":{"Verfasst von":"der huflaikhan","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/"},"author":{"name":"der huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"headline":"Versteigerung von Musiknutzungsrechten","datePublished":"2006-05-30T15:07:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/"},"wordCount":486,"commentCount":0,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#primaryimage"},"thumbnailUrl":"","keywords":["Copyright","ebay","Nutzungsrechte","Urheberrecht","Versteigerung"],"articleSection":["das Urheberrecht","die Musik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/","name":"Versteigerung von Musiknutzungsrechten - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#primaryimage"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2006-05-30T15:07:22+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"Versteigerung von Musiknutzungsrechten"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/martin_d1juqiu5\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":["das Urheberrecht","die Musik"],"post_class":[["post-8326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-das-urheberrecht","category-diemusik","tag-copyright","tag-ebay","tag-nutzungsrechte","tag-urheberrecht","tag-versteigerung","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":1754,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten\/","url_meta":{"origin":8326,"position":0},"title":"Versteigerung von Musiknutzungsrechten","author":"huflaikhan","date":"30. Mai 2006","format":false,"excerpt":"Heute in der Mailpost. Da versteigert einer einen Popsong mit interessanten Nebenaspekten. Am Dienstag, den 30.Mai, 14 Uhr MESZ, beginnt auf E-Bay Deutschland die weltweit erste Versteigerung von Nutzungsrechten eines Musiktitels. Der H\u00f6chstbietende erwirbt die Rechte zur deutschlandweiten Vermarktung des Titels \u00fcber s\u00e4mtliche Vertriebskan\u00e4le - CD, Internet, Mobiltelefone, Klingelt\u00f6ne, Film\u2026","rel":"","context":"Mit 6 Kommentaren","block_context":{"text":"Mit 6 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/05\/versteigerung-von-musiknutzungsrechten\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8279,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/11\/nutzungswert-enzyklopaedie-der-kritischen-masse\/","url_meta":{"origin":8326,"position":1},"title":"Nutzungswert [Enzyklop\u00e4die der Kritischen Masse]","author":"der huflaikhan","date":"15. November 2004","format":false,"excerpt":"Die heutige Pressemeldung aus dem Hause der Deutschen Phonoverb\u00e4nde mit dem Titel:\u00a0Forum der Rechteinhaber fordert angemessene pauschale Verg\u00fctungen und effektivere Regeln zur Pirateriebek\u00e4mpfung im Urheberrechtsgesetz\u00a0ist ein bisschen pikant. Die pauschalen Verg\u00fctungen auf Ger\u00e4ten und Leermedien befinden sich auf dem Stand von 1985. Die Bundesregierung hat bereits in zwei Verg\u00fctungsberichten festgestellt,\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8386,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/starkes-urheberrecht-schwacher-schutz-2\/","url_meta":{"origin":8326,"position":2},"title":"Starkes Urheberrecht &#8211; schwacher Schutz","author":"der huflaikhan","date":"5. August 2012","format":false,"excerpt":"Der Deutsche Kulturrat will in Sachen Urheberrecht eine gute Figur machen. Kultur lebt ja auch von vielen Urhebern. Aber wovon leben die Urheber: Von der Kultur ihrer Vertreter? Das kann es wohl nicht sein. Sonst w\u00e4ren die Urheber noch \u00e4rmer. Ein trauriges Kapitel kultureller Autokannibalisierung. Viele meinen es mit den\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"Urheberrechte abh\u00e4ngen mit dem Deutschen Kulturrat. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/08\/kulturrat.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/08\/kulturrat.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/08\/kulturrat.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/08\/kulturrat.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2661,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2012\/08\/starkes-urheberrecht-schwacher-schutz\/","url_meta":{"origin":8326,"position":3},"title":"Starkes Urheberrecht &#8211; schwacher Schutz","author":"huflaikhan","date":"5. August 2012","format":false,"excerpt":"Der Deutsche Kulturrat will in Sachen Urheberrecht eine gute Figur machen. Kultur lebt ja auch von vielen Urhebern. Aber wovon leben die Urheber: Von der Kultur ihrer Vertreter? Das kann es wohl nicht sein. Sonst w\u00e4ren die Urheber noch \u00e4rmer. Ein trauriges Kapitel kultureller Autokannibalisierung. Viele meinen es mit den\u2026","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Urheberrechte abh\u00e4ngen mit dem Deutschen Kulturrat. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/kulturrat.jpg?fit=1200%2C801&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/kulturrat.jpg?fit=1200%2C801&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/kulturrat.jpg?fit=1200%2C801&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/kulturrat.jpg?fit=1200%2C801&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2012\/08\/kulturrat.jpg?fit=1200%2C801&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8245,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/06\/pauschalverguetungen-fuers-netz-2\/","url_meta":{"origin":8326,"position":4},"title":"Pauschalverg\u00fctungen f\u00fcrs Netz","author":"der huflaikhan","date":"22. Juni 2004","format":false,"excerpt":"Langsam formieren sich die Verfechter des Prinzips der Pauschalverg\u00fctung f\u00fcr urheberrechtlich gesch\u00fctzte Werke im Internet. Ganz druckfrisch ist eine Stellungnahme unter dem Titel \u201cKompensation ohne Kontrolle\u201d (Stellungnahme zum Zweiten Korb der Novellierung des Urheberrechtsgesetzes) ander beteiligt sind: privatkopie.net, Forum Informatikerinnen f\u00fcr Frieden und gesellschaftliche Verantwortung e.V.(FIfF), Netzwerk Neue Medien, Chaos\u2026","rel":"","context":"In &quot;das Recht&quot;","block_context":{"text":"das Recht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-recht\/"},"img":{"alt_text":"Privatkopie. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2018\/06\/klavier_innen_mit_schrauben_c_hufner-09-1024x768.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":490,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/06\/pauschalverguetungen-fuers-netz\/","url_meta":{"origin":8326,"position":5},"title":"Pauschalverg\u00fctungen f\u00fcrs Netz","author":"huflaikhan","date":"22. Juni 2004","format":false,"excerpt":"Langsam formieren sich die Verfechter des Prinzips der Pauschalverg\u00fctung f\u00fcr urheberrechtlich gesch\u00fctzte Werke im Internet. Ganz druckfrisch ist eine Stellungnahme unter dem Titel \u201cKompensation ohne Kontrolle\u201d (Stellungnahme zum Zweiten Korb der Novellierung des Urheberrechtsgesetzes) ander beteiligt sind: privatkopie.net, Forum Informatikerinnen f\u00fcr Frieden und gesellschaftliche Verantwortung e.V.(FIfF), Netzwerk Neue Medien, Chaos\u2026","rel":"","context":"Mit 9 Kommentaren","block_context":{"text":"Mit 9 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/06\/pauschalverguetungen-fuers-netz\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/8326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=8326"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/8326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/1009"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=8326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=8326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=8326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}