{"id":8534,"date":"2015-02-17T18:28:50","date_gmt":"2015-02-17T17:28:50","guid":{"rendered":"http:\/\/blogs.nmz.de\/wm2014\/?p=1254"},"modified":"2015-02-17T18:28:50","modified_gmt":"2015-02-17T17:28:50","slug":"traurige-tweets-orchesterkultur","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2015\/02\/traurige-tweets-orchesterkultur\/","title":{"rendered":"Traurige Tweets \u2013 Orchesterkultur"},"content":{"rendered":"<p>Wir wissen bis heute noch nicht, wof\u00fcr Twitter jetzt mal so gut ist. Obwohl: Wissen wir schon. Kurznachrichtendienst, sagen die sogenannten Leitmedien mit ihrem qualit\u00e4tsgetr\u00e4nkten Leitjournalismus. Die nmz ist bei Twitter \u00fcbrigens auch pr\u00e4sent mit \u00fcber 3.600 Followern (@musikzeitung) und einem Strau\u00df von Kurznachrichten, \u00fcbrigens schon knapp 15.000 Tweets. Das ist wahscheinlich toll.<\/p>\n<p>Und ja, wir nutzen das auch, um Kurznachrichten zu senden \u2013 und zu lesen. Heute lasen wir das:<\/p>\n<p>https:\/\/twitter.com\/SWR2\/status\/567690944061767680<\/p>\n<p>Das ist wirklich ein netter Zug des SWR. <a href=\"http:\/\/www.la8.de\/de\/museum.html\" target=\"_blank\" rel=\"noopener noreferrer\">Man k\u00fcmmert sich um die Berliner Philharmoniker<\/a>. Was die Nachricht verschweigt: Die Berliner bereiten gerade eine Gegenausstellung vor. Diese zeigt im April die Entstehung der SWR-Orchester &amp; und deren Abstieg zu einem Abwicklungsorchester. Im M\u00e4nnerklo, direkt unterhalb des Seifenspenders. Bin mal gespannt, ob die das dann auch so akkurat melden, da, beim SWR.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Traurige%20Tweets%20%E2%80%93%20Orchesterkultur https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2015%2F02%2Ftraurige-tweets-orchesterkultur%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2015%2F02%2Ftraurige-tweets-orchesterkultur%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Traurige%20Tweets%20%E2%80%93%20Orchesterkultur https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2015%2F02%2Ftraurige-tweets-orchesterkultur%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Traurige%20Tweets%20%E2%80%93%20Orchesterkultur%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2015%2F02%2Ftraurige-tweets-orchesterkultur%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button rss shariff-nocustomcolor\" style=\"background-color:#ff8c00\"><a href=\"https:\/\/www.kritische-masse.de\/logbuch\/feed\/rss\/\" title=\"RSS-feed\" aria-label=\"RSS-feed\" role=\"button\" class=\"shariff-link\" style=\"; background-color:#fe9312; color:#fe9312\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#fe9312\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fe9312\" d=\"M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#fe9312\">RSS-feed<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Wir wissen bis heute noch nicht, wof\u00fcr Twitter jetzt mal so gut ist. Obwohl: Wissen wir schon. Kurznachrichtendienst, sagen die sogenannten Leitmedien mit ihrem qualit\u00e4tsgetr\u00e4nkten Leitjournalismus. Die nmz ist bei Twitter \u00fcbrigens auch pr\u00e4sent mit \u00fcber 3.600 Followern (@musikzeitung) und einem Strau\u00df von Kurznachrichten, \u00fcbrigens schon knapp 15.000 Tweets. Das ist wahscheinlich toll. Und ja, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_metis_text_type":"standard","_metis_text_length":1075,"_post_count":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3488,2649,2695,2652,3545],"tags":[2452,3504,2666,3384],"class_list":["post-8534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administratives","category-denrundfunk","category-die-kultur","category-diemusik","category-medien","tag-kultur","tag-orchester","tag-swr","tag-swr-orchester","entry","has-media"],"desktop_mode_lock":null,"desktop_mode_contributors":[],"desktop_mode_attached_media":[1255],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2005\/06\/20050602-klotz1.jpg?fit=200%2C135&ssl=1","categories_names":["Administratives","den Rundfunk","die Kultur","die Musik","die Medien"],"post_class":[["post-8534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-administratives","category-denrundfunk","category-die-kultur","category-diemusik","category-medien","tag-kultur","tag-orchester","tag-swr","tag-swr-orchester","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":8472,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/08\/orchesterabschaffer-boudgoust-freut-sich\/","url_meta":{"origin":8534,"position":0},"title":"Orchesterabschaffer Boudgoust freut sich","author":"der huflaikhan","date":"28. August 2014","format":false,"excerpt":"Das SWR-Orchester Freiburg und Baden-Baden hat einen v\u00f6llig unn\u00fctzen Preis erhalten: Den ECHO Klassik. Dessen kulturpolitische Bedeutung ist zwar gleich Null, aber seine \u00f6ffentliche Pr\u00e4senz ist hoch; die BILD-Zeitung wird ja auch von vielen sehr gesch\u00e4tzt. Das Orchester, das es bald nicht mehr gibt, weil der Intendant des SWR, Peter\u2026","rel":"","context":"In &quot;die Kultur&quot;","block_context":{"text":"die Kultur","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/die-kultur\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8682,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2016\/09\/das-trojanische-orchester-und-die-deutsche-orchesterverweigerung\/","url_meta":{"origin":8534,"position":1},"title":"Das trojanische Orchester und die Deutsche Orchesterverweigerung","author":"der huflaikhan","date":"28. September 2016","format":false,"excerpt":"Der Clou mit dem trojanischen Pferd war ein l\u00e4cherlicher Trick dagegen. Mit dem SWR Symphonieorchester hat Deutschland endlich seine eierlegende Wollmilchsau gefunden. Es ist besser als anderen deutschen Rundfunkorchester zusammen, weil auch gr\u00f6\u00dfer und aus zwei hervorragenden Orchestern zusammengesetzt \u2013 die einen nennen es noch wehm\u00fctig fusioniert, die anderen ganz\u2026","rel":"","context":"In &quot;\u00c4sthetische Kunstfehler&quot;","block_context":{"text":"\u00c4sthetische Kunstfehler","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/aesthetische_kunstfehler\/"},"img":{"alt_text":"opfer m\u00fcssen begracht werden. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2016\/09\/salome1-1024x353.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3341,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/03\/kultur-manager-kulturabwickler\/","url_meta":{"origin":8534,"position":2},"title":"Kultur-Manager = Kulturabwickler","author":"huflaikhan","date":"25. M\u00e4rz 2014","format":false,"excerpt":"F\u00fcr die Fusion seiner Orchester hat sich der SWR ja einen Mann geholt, der das machen soll. Der hat seine Arbeit mit Henze, mit M\u00f6lich-Zebhauser, dem Konzerthaus Essen und anderen Institutionen absolviert. Der darf die Fusion durchf\u00fchren. Er wusste das auch. Vielleicht macht er es nicht gern, aber er wird\u2026","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Orchesterzukunft-Geblubber. Grafik: SWR","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/03\/swr.jpg?fit=512%2C200&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":8697,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2016\/09\/133-827-69380-euro\/","url_meta":{"origin":8534,"position":3},"title":"133.827.693,80 Euro","author":"der huflaikhan","date":"27. September 2016","format":false,"excerpt":"Das ist angeblich der Preis, den die ARD f\u00fcr die Bundesligasenderechte im Jahr aufwendet, so meldet es die FAZ, die sich auf die taz bezieht. Wem das komisch vorkommt, der liegt nicht ganz falsch. Denn eine Transparenz unserer (!) \u00f6ffentlich-rechtlichen Sender scheint in diesem Punkt nicht auffindbar zu sein. Ganz\u2026","rel":"","context":"In &quot;den Rundfunk&quot;","block_context":{"text":"den Rundfunk","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/denrundfunk\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":9930,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2024\/07\/eskalation-oder-erklaerung\/","url_meta":{"origin":8534,"position":4},"title":"Eskalation oder Erkl\u00e4rung","author":"der huflaikhan","date":"18. Juli 2024","format":false,"excerpt":"Auch die Berichterstattung in der Musikszene ger\u00e4t immer mehr ins Kreuzfeuer ihrer eigenen Darstellungsformen. Mit Axel Br\u00fcggemanns neuem \u2013 wie sagt man \u2013 Blog, News-, Kommentar- und Meinungsportal \u201eBackstageClassical\u201c aus Bremen ist das nicht anders als mit dem \u201eVan-Magazin\u201c aus Berlin. Nur dass das eine w\u00f6chentlich Texte hinter einer Paywall\u2026","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Ich wei\u00df jetzt auch nicht mehr. \u00a9 MH","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/07\/Ich-weiss-jetzt-auch-nicht-mehr.-%C2%A9-MH.jpg?fit=717%2C717&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/07\/Ich-weiss-jetzt-auch-nicht-mehr.-%C2%A9-MH.jpg?fit=717%2C717&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/07\/Ich-weiss-jetzt-auch-nicht-mehr.-%C2%A9-MH.jpg?fit=717%2C717&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/07\/Ich-weiss-jetzt-auch-nicht-mehr.-%C2%A9-MH.jpg?fit=717%2C717&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8636,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2016\/01\/vergifteter-nachruf\/","url_meta":{"origin":8534,"position":5},"title":"Vergifteter Nachruf","author":"der huflaikhan","date":"15. Januar 2016","format":false,"excerpt":"SWR Intendant Peter Boudgoust zum Tod von Pierre Boulez: \u201eDer Name Pierre Boulez steht f\u00fcr die zeitgen\u00f6ssische Musik wie kaum ein Zweiter. Er hat Generationen von Musikern und Musikliebhabern befl\u00fcgelt, als Dirigent und als Komponist gleicherma\u00dfen. Unvergessen bleiben neben seinen vielf\u00e4ltigen internationalen Engagements auch die von ihm geleiteten Urauff\u00fchrungen bei\u2026","rel":"","context":"In &quot;den Rundfunk&quot;","block_context":{"text":"den Rundfunk","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/denrundfunk\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/8534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=8534"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/8534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media\/1255"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=8534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=8534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=8534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}