{"id":854,"date":"2004-10-25T10:19:07","date_gmt":"2004-10-25T09:19:07","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/weber-im-zusammenhang-191920\/"},"modified":"2023-12-18T08:49:30","modified_gmt":"2023-12-18T07:49:30","slug":"weber-im-zusammenhang-191920","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/","title":{"rendered":"Weber im Zusammenhang (1919\/20)"},"content":{"rendered":"<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Weber%20im%20Zusammenhang%20%281919%2F20%29 https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Weber%20im%20Zusammenhang%20%281919%2F20%29 https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Weber%20im%20Zusammenhang%20%281919%2F20%29%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div><p>Der <a href=\"http:\/\/luebue.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">Haltungsturner<\/a> fragt nach dem Zusammenhang eines in der Kritischen Masse notierten <a href=\"http:\/\/www.kritische-masse.de\/blog\/item\/622#comm\">Zitats<\/a>: Ich mag das nicht im Kommentar beantworten, sondern unter einem eigenen Punkt. <\/p>\n<p>Bei dem Text handelt es sich um den Schlussabschnitt aus der Aufsatzsammlung &#8222;Die protestantische Ethik&#8220; und hier genauer der erste Aufsatz &#8222;Die protestantische Ethik und der Geist des Kapitalismus&#8220;. Max Weber ist l\u00e4ngst ein &#8222;Klassiker&#8220; der modernen Soziologie und entschprechend dick ist die Sekund\u00e4rliteratur. Damit kann ich mich nicht messen und rezipiert habe ich die abgeleiteten Werk auch nicht, es sei denn, Webers Analyse des Rationalismus ist Bestandteil anderer Werke gewesen &#8212; zum Beispiel in Habermas&#8217; &#8222;Theorie des kommunikativen Handels.&#8220;<\/p>\n<p>Im groben Umriss, das macht auch das ausf\u00fchrliche Zitat deutlich, geht es um die Entwicklung des Berufsmenschentum. Askese als eine Grundlage der M\u00f6glichkeit zur Entwicklung rationalen Handelns, wie sie sich in Handlungsleitungen im Protestantismus ausgebildet hat. Diese Bewegung, ich paraphrasiere das sehr zugespitzt, machte erst Wissenschaft m\u00f6glich, die Entwicklung der abendl\u00e4ndischen Kunst, <br \/>\n<cite>Das musikalische Geh\u00f6r war bei anderen V\u00f6lkern anscheinend eher feiner entwickelt als heute bei uns; jedenfalls nicht minder fein. Polyphonie verschiedener Art war weithin \u00fcber die Erde verbreitet, Zusammenwirken einer Mehrheit von Instrumenten und auch das Diskantieren findet sich anderw\u00e4rts. Alle unsere rationalen Tonintervalle waren auch anderw\u00e4rts berechnet und bekannt. Aber rationale harmonische Musik (&#8230;) dies alles gab es nur im Okzident.<br \/>\n<cite><i>Max Weber: Vorbemerkung (zu seinen Gesammelten Aufs\u00e4tzen zur Religionssoziologie), in: Die protestantische Ethik I, G\u00fctersloh <sup>6<\/sup>1981, S. 10.<\/i><\/cite><\/cite><br \/>\ndas Beamtentum, den modernen Staat mit seinen vielfach rational verwobenen Elementen. &#8222;Es liegt in unserer Hand, was wir aus der Welt machen&#8220;, so simpel w\u00fcrde ich herunterrechnen. Die Elemente des Rationalismus bieten dabei die M\u00f6glichkeit zur Kritik und Verbesserung. Wir k\u00f6nnen \u00fcber unsere Probleme reden, als Probleme, die wir selbst hervorbringen. Das ist in anderen gesellschaftlichen Entwicklungslinien anders, wo \u00e4u\u00dfere M\u00e4chte das Leben f\u00fcr uns bestimmen. (Wie gesagt, alles sehr schematisch verk\u00fcrzt). <\/p>\n<p>Sieht Weber das von seinem Ursprung her noch als eine Entscheidung [von Subjekten (zu stark), von Personen (naja), von Individuen (das wollen sie ja erst werden); schwierig], so sind wir in diesen Geist hineingeborenen dem einfach ausgesetzt [dem Schein und Selbstschein nach Individuen]. Es gibt keine M\u00f6glichkeit zum Abschied vom Rationalismus. Damit wird aber &#8222;Rationalismus&#8220; aus ihrer positiven Bestimmung zu einem Verh\u00e4ngnis. Weber nennt dies das &#8222;stahlharte Geh\u00e4use [der H\u00f6rigkeit]&#8220;. <\/p>\n<p>Gleichzeitig diagnostiziert Weber, dass dadurch aber alle Gegenst\u00e4nde der Lebenswelt sich zu &#8222;G\u00fctern&#8220; verwandeln. G\u00fcter sind handelbar und sind &#8222;nur noch&#8220; handelbar. Sie haben keinen Wert f\u00fcr sich, sondern nur im Zusammenhang mit Handlungen. Das ist eine Entwicklung zunehmender Versachlichung. <\/p>\n<p>Was so erstaunlich ist bei Webers Text, ist, dass er sich hier &#8212; man m\u00f6chte fast sagen &#8212; zu wissenschaftlicher Prosa hinei\u00dfen l\u00e4sst. Einer, der sehr sparsam umgeht mit moralischen Werturteilen, zieht eine in der Tat prophetische Bilanz. Er sieht das auch sofort und federd ab: &#8222;Doch wir geraten damit auf das Gebiet der Wert- und Glaubensurteile, mit welchen diese rein historische Darstellung nicht belastet werden soll.&#8220; So ist aber dennoch die Passage typisches Beispiel einer sich entwickelnden Kulturkritik, wie sie sp\u00e4ter Adorno auf die Spitze getrieben hat, wie sie sich aber auch gerade in den 50er und 60er Jahren des letzten Jahrhundert an vielen Stellen \u00e4u\u00dferte (Jaspers, Gehlen, Amery, Arendt, Russell, Sonnemann, Anders \u0085), vor allem in der Konsequenz, dass in einer &#8222;aufgekl\u00e4rten&#8220; Welt etwas wie der Nationalsozialismus mit seiner rationalen T\u00f6tungsmaschinerie und Enthirnung der Subjekte \u00fcberhaupt sich ereignen konnte. <\/p>\n<p>Man vergisst dies in der heutigen Zeit, wo sich der Kapitalismus immer wieder neu als gesellschaftliches L\u00f6sunngsmodell anbietet als alleinseligmachendes gesellschaftliches Prinzip. Marx und Engels hatten diese positive Aura im 19. Jahrhundert heftig kritisiert. Die neuen Kriege am in der zweiten H\u00e4lfte des 20. Jahrhunderts ebenso wie die emotional verdr\u00e4ngte Wirtschaftskatastrophe der &#8222;schwarzen Tage&#8220; beim New Yorker B\u00f6rsencrash vor ziemlich genau 75 Jahren sind ebenso Effekte dieser Entwicklung. Auch das nur zur Erinnerung &#8212; man vergisst dergleichen gerne und sehr schnell. <\/p>\n<p>Nun aber der wirklich aufregende Text Webers im Zusammenhang:<br \/>\n<!--break--><br \/>\n<cite>Der Puritaner <i>wollte<\/i> Berufsmensch sein, &#8212; wir <i>m\u00fcssen<\/i> es sein. Denn indem die Askese aus den M\u00f6nchszellen heraus in das Berufsleben \u00fcbertragen wurde und die innerweltliche Sittlichkeit jenen m\u00e4chtigen Kosmos der modernen, an die technischen und \u00f6konomischen Voraussetzungen mechanisch-maschineller Produktion gebundenen, Wirtschaftsordnung zu erbauen, der heute den Lebensstil aller Einzelnen, die in dieses Triebwerk hineingeboren werden \u0096- <i>nicht<\/i> nur der direkt \u00f6konomischen Erwerbst\u00e4tigen &#8211;, mit \u00fcberw\u00e4ltigendem Zwange bestimmt und vielleicht bestimmen wird, bis der letzte Zentner fossilen Brennstoffs vergl\u00fcht ist. Nur wie \u00bbein d\u00fcnner Mantel, den man jederzeit abwerfen k\u00f6nnte\u00ab, sollte nach baxters Ansicht die Sorge um die \u00e4u\u00dferen G\u00fcter um die Schultern seiner Heiligen liegen. Aber aus dem Mantel lie\u00df das Verh\u00e4ngnis ein stahlhartes Geh\u00e4use werden. Indem die Askese die Welt umzubauen und in der Welt sich auszuwirken unternahm, gewannen die \u00e4u\u00dferen G\u00fcter dieser Welt zunehmende und schlie\u00dflich unentrinnbare Macht \u00fcber den Menschen, wie niemals zuvor in der Geschichte. Heute ist ihr Geist &#8212; ob endg\u00fcltig, wer wei\u00df es? &#8212; aus diesem Geh\u00e4use entwichen. Der siegreiche Kapitalismus jedenfalls bedarf, seit er auf mechanischer Grundlage ruht, dieser St\u00fctze nicht mehr. Auch die rosige Stimmung ihrer lachenden Erbin: der Aufkl\u00e4rung, scheint endg\u00fcltig im Verbleichen, und als ein Gespenst ehemals religi\u00f6ser Glaubensinhalte geht der Gedanke der \u00bbBerufspflicht\u00ab in unserm Leben um. Wo die \u00bbBerufserf\u00fcllung\u00ab nicht direkt zu den h\u00f6chsten geistigen Kulturwerten in Beziehung gesetzt werden kann &#8212; oder wo nicht umgekehrt: sie auch subjektiv einfach als \u00f6konomischer Zwang empfunden werden mu\u00df &#8211;, da verzichtet der Einzelne heute meist auf ihre Ausdeutung \u00fcberhaupt. Auf dem Gebiet seiner h\u00f6chsten Entfesselung, in den Vereinigten Staaten, neigt das seines religi\u00f6s-ethischen Sinnes entkleidete Erwerbsstreben heute dazu, sich mit rein agonalen Leidenschaften zu assoziieren, die ihm nicht selten geradezu den Charakter des Sports aufpr\u00e4gen. Niemand wei\u00df noch, wer k\u00fcnftig in jenem Geh\u00e4use wohnen wird und ob am Ende dieser ungeheuren Entwicklung ganz neue Prophetien oder eine m\u00e4chtige Wiedergeburt alter Gedanken und Ideale stehen werden, <i>oder<\/i> aber &#8211; wenn keins von beiden &#8212; mechanisierte Versteinerung, mit einer Art von klampfhaftem Sich-wichtignehmen verbr\u00e4mt. Dann allerdings k\u00f6nnte f\u00fcr die \u00bbletzten Menschen\u00ab dieser Kulturentwicklung das Wort zur Wahrheit werden: \u00bbFachmenschen ohne Geist, Genu\u00dfmenschen ohne Herz: dies Nichts bildet sich ein, eine nie vorher erreichte Stufe des Menschentums erstiegen zu haben.\u00ab*<\/p>\n<p>Doch wir geraten damit auf das Gebiet der Wert- und Glaubensurteile, mit welchen diese rein historische Darstellung nicht belastet werden soll. Die <i>Aufgabe<\/i> w\u00e4re vielmehr: die in der vorstehenden Skizze ja nur angeschnittene Bedeutung des asketischen Rationalismus nun auch f\u00fcr den Inhalt der <i>sozialpolitischen<\/i> Ethik, also f\u00fcr die Art der Organisation und der Funktionen der sozialen Gemeinschaften vom Konventikel bis zum Staat aufzuzeigen. Alsdann m\u00fc\u00dfte seine Beziehung zu dem humanistischen Rationalismus und dessen Lebensidealen und Kultureinfl\u00fcssen, femer zur Entwicklung des philosophischen und wissenschaftlichen Empirismus, zu der technischen Entwicklung und zu den geistigen Kulturg\u00fctern analysiert werden. Dann endlich w\u00e4re sein geschichtliches Werden von den mittelalterlichen Ans\u00e4tzen einer innerweltlichen Askese an und seine Aufl\u00f6sung in den reinen Utilitarismus <i>historisch<\/i> und durch die einzelnen Verbreitungsgebiete der asketischen Religiosit\u00e4t hindurch zu verfolgen. Daraus erst k\u00f6nnte sich das <i>Ma\u00df<\/i> der Kulturbedeutung des asketischen Protestantismus im Verh\u00e4ltnis zu anderen plastischen Elementen der modernen Kultur ergeben. <br \/>\n<cite><i>Max Weber: Die protestantische Ethik und der Geist des Kapitalismus, in: Die protestantische Ethik I, G\u00fctersloh <sup>6<\/sup>1981, S. 188 f..<\/i><\/cite><\/cite><br \/>\n<!--more--><br \/>\nDer <a href=\"http:\/\/luebue.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">Haltungsturner<\/a> fragt nach dem Zusammenhang eines in der Kritischen Masse notierten <a href=\"http:\/\/www.kritische-masse.de\/blog\/item\/622#comm\">Zitats<\/a>: Ich mag das nicht im Kommentar beantworten, sondern unter einem eigenen Punkt. <\/p>\n<p>Bei dem Text handelt es sich um den Schlussabschnitt aus der Aufsatzsammlung &#8222;Die protestantische Ethik&#8220; und hier genauer der erste Aufsatz &#8222;Die protestantische Ethik und der Geist des Kapitalismus&#8220;. Max Weber ist l\u00e4ngst ein &#8222;Klassiker&#8220; der modernen Soziologie und entschprechend dick ist die Sekund\u00e4rliteratur. Damit kann ich mich nicht messen und rezipiert habe ich die abgeleiteten Werk auch nicht, es sei denn, Webers Analyse des Rationalismus ist Bestandteil anderer Werke gewesen &#8212; zum Beispiel in Habermas&#8217; &#8222;Theorie des kommunikativen Handels.&#8220;<\/p>\n<p>Im groben Umriss, das macht auch das ausf\u00fchrliche Zitat deutlich, geht es um die Entwicklung des Berufsmenschentum. Askese als eine Grundlage der M\u00f6glichkeit zur Entwicklung rationalen Handelns, wie sie sich in Handlungsleitungen im Protestantismus ausgebildet hat. Diese Bewegung, ich paraphrasiere das sehr zugespitzt, machte erst Wissenschaft m\u00f6glich, die Entwicklung der abendl\u00e4ndischen Kunst, <br \/>\n<cite>Das musikalische Geh\u00f6r war bei anderen V\u00f6lkern anscheinend eher feiner entwickelt als heute bei uns; jedenfalls nicht minder fein. Polyphonie verschiedener Art war weithin \u00fcber die Erde verbreitet, Zusammenwirken einer Mehrheit von Instrumenten und auch das Diskantieren findet sich anderw\u00e4rts. Alle unsere rationalen Tonintervalle waren auch anderw\u00e4rts berechnet und bekannt. Aber rationale harmonische Musik (&#8230;) dies alles gab es nur im Okzident.<br \/>\n<cite><i>Max Weber: Vorbemerkung (zu seinen Gesammelten Aufs\u00e4tzen zur Religionssoziologie), in: Die protestantische Ethik I, G\u00fctersloh <sup>6<\/sup>1981, S. 10.<\/i><\/cite><\/cite><br \/>\ndas Beamtentum, den modernen Staat mit seinen vielfach rational verwobenen Elementen. &#8222;Es liegt in unserer Hand, was wir aus der Welt machen&#8220;, so simpel w\u00fcrde ich herunterrechnen. Die Elemente des Rationalismus bieten dabei die M\u00f6glichkeit zur Kritik und Verbesserung. Wir k\u00f6nnen \u00fcber unsere Probleme reden, als Probleme, die wir selbst hervorbringen. Das ist in anderen gesellschaftlichen Entwicklungslinien anders, wo \u00e4u\u00dfere M\u00e4chte das Leben f\u00fcr uns bestimmen. (Wie gesagt, alles sehr schematisch verk\u00fcrzt). <\/p>\n<p>Sieht Weber das von seinem Ursprung her noch als eine Entscheidung [von Subjekten (zu stark), von Personen (naja), von Individuen (das wollen sie ja erst werden); schwierig], so sind wir in diesen Geist hineingeborenen dem einfach ausgesetzt [dem Schein und Selbstschein nach Individuen]. Es gibt keine M\u00f6glichkeit zum Abschied vom Rationalismus. Damit wird aber &#8222;Rationalismus&#8220; aus ihrer positiven Bestimmung zu einem Verh\u00e4ngnis. Weber nennt dies das &#8222;stahlharte Geh\u00e4use [der H\u00f6rigkeit]&#8220;. <\/p>\n<p>Gleichzeitig diagnostiziert Weber, dass dadurch aber alle Gegenst\u00e4nde der Lebenswelt sich zu &#8222;G\u00fctern&#8220; verwandeln. G\u00fcter sind handelbar und sind &#8222;nur noch&#8220; handelbar. Sie haben keinen Wert f\u00fcr sich, sondern nur im Zusammenhang mit Handlungen. Das ist eine Entwicklung zunehmender Versachlichung. <\/p>\n<p>Was so erstaunlich ist bei Webers Text, ist, dass er sich hier &#8212; man m\u00f6chte fast sagen &#8212; zu wissenschaftlicher Prosa hinei\u00dfen l\u00e4sst. Einer, der sehr sparsam umgeht mit moralischen Werturteilen, zieht eine in der Tat prophetische Bilanz. Er sieht das auch sofort und federd ab: &#8222;Doch wir geraten damit auf das Gebiet der Wert- und Glaubensurteile, mit welchen diese rein historische Darstellung nicht belastet werden soll.&#8220; So ist aber dennoch die Passage typisches Beispiel einer sich entwickelnden Kulturkritik, wie sie sp\u00e4ter Adorno auf die Spitze getrieben hat, wie sie sich aber auch gerade in den 50er und 60er Jahren des letzten Jahrhundert an vielen Stellen \u00e4u\u00dferte (Jaspers, Gehlen, Amery, Arendt, Russell, Sonnemann, Anders \u0085), vor allem in der Konsequenz, dass in einer &#8222;aufgekl\u00e4rten&#8220; Welt etwas wie der Nationalsozialismus mit seiner rationalen T\u00f6tungsmaschinerie und Enthirnung der Subjekte \u00fcberhaupt sich ereignen konnte. <\/p>\n<p>Man vergisst dies in der heutigen Zeit, wo sich der Kapitalismus immer wieder neu als gesellschaftliches L\u00f6sunngsmodell anbietet als alleinseligmachendes gesellschaftliches Prinzip. Marx und Engels hatten diese positive Aura im 19. Jahrhundert heftig kritisiert. Die neuen Kriege am in der zweiten H\u00e4lfte des 20. Jahrhunderts ebenso wie die emotional verdr\u00e4ngte Wirtschaftskatastrophe der &#8222;schwarzen Tage&#8220; beim New Yorker B\u00f6rsencrash vor ziemlich genau 75 Jahren sind ebenso Effekte dieser Entwicklung. Auch das nur zur Erinnerung &#8212; man vergisst dergleichen gerne und sehr schnell. <\/p>\n<p>Nun aber der wirklich aufregende Text Webers im Zusammenhang:<br \/>\n<!--break--><br \/>\n<cite>Der Puritaner <i>wollte<\/i> Berufsmensch sein, &#8212; wir <i>m\u00fcssen<\/i> es sein. Denn indem die Askese aus den M\u00f6nchszellen heraus in das Berufsleben \u00fcbertragen wurde und die innerweltliche Sittlichkeit jenen m\u00e4chtigen Kosmos der modernen, an die technischen und \u00f6konomischen Voraussetzungen mechanisch-maschineller Produktion gebundenen, Wirtschaftsordnung zu erbauen, der heute den Lebensstil aller Einzelnen, die in dieses Triebwerk hineingeboren werden \u0096- <i>nicht<\/i> nur der direkt \u00f6konomischen Erwerbst\u00e4tigen &#8211;, mit \u00fcberw\u00e4ltigendem Zwange bestimmt und vielleicht bestimmen wird, bis der letzte Zentner fossilen Brennstoffs vergl\u00fcht ist. Nur wie \u00bbein d\u00fcnner Mantel, den man jederzeit abwerfen k\u00f6nnte\u00ab, sollte nach baxters Ansicht die Sorge um die \u00e4u\u00dferen G\u00fcter um die Schultern seiner Heiligen liegen. Aber aus dem Mantel lie\u00df das Verh\u00e4ngnis ein stahlhartes Geh\u00e4use werden. Indem die Askese die Welt umzubauen und in der Welt sich auszuwirken unternahm, gewannen die \u00e4u\u00dferen G\u00fcter dieser Welt zunehmende und schlie\u00dflich unentrinnbare Macht \u00fcber den Menschen, wie niemals zuvor in der Geschichte. Heute ist ihr Geist &#8212; ob endg\u00fcltig, wer wei\u00df es? &#8212; aus diesem Geh\u00e4use entwichen. Der siegreiche Kapitalismus jedenfalls bedarf, seit er auf mechanischer Grundlage ruht, dieser St\u00fctze nicht mehr. Auch die rosige Stimmung ihrer lachenden Erbin: der Aufkl\u00e4rung, scheint endg\u00fcltig im Verbleichen, und als ein Gespenst ehemals religi\u00f6ser Glaubensinhalte geht der Gedanke der \u00bbBerufspflicht\u00ab in unserm Leben um. Wo die \u00bbBerufserf\u00fcllung\u00ab nicht direkt zu den h\u00f6chsten geistigen Kulturwerten in Beziehung gesetzt werden kann &#8212; oder wo nicht umgekehrt: sie auch subjektiv einfach als \u00f6konomischer Zwang empfunden werden mu\u00df &#8211;, da verzichtet der Einzelne heute meist auf ihre Ausdeutung \u00fcberhaupt. Auf dem Gebiet seiner h\u00f6chsten Entfesselung, in den Vereinigten Staaten, neigt das seines religi\u00f6s-ethischen Sinnes entkleidete Erwerbsstreben heute dazu, sich mit rein agonalen Leidenschaften zu assoziieren, die ihm nicht selten geradezu den Charakter des Sports aufpr\u00e4gen. Niemand wei\u00df noch, wer k\u00fcnftig in jenem Geh\u00e4use wohnen wird und ob am Ende dieser ungeheuren Entwicklung ganz neue Prophetien oder eine m\u00e4chtige Wiedergeburt alter Gedanken und Ideale stehen werden, <i>oder<\/i> aber &#8211; wenn keins von beiden &#8212; mechanisierte Versteinerung, mit einer Art von klampfhaftem Sich-wichtignehmen verbr\u00e4mt. Dann allerdings k\u00f6nnte f\u00fcr die \u00bbletzten Menschen\u00ab dieser Kulturentwicklung das Wort zur Wahrheit werden: \u00bbFachmenschen ohne Geist, Genu\u00dfmenschen ohne Herz: dies Nichts bildet sich ein, eine nie vorher erreichte Stufe des Menschentums erstiegen zu haben.\u00ab*<\/p>\n<p>Doch wir geraten damit auf das Gebiet der Wert- und Glaubensurteile, mit welchen diese rein historische Darstellung nicht belastet werden soll. Die <i>Aufgabe<\/i> w\u00e4re vielmehr: die in der vorstehenden Skizze ja nur angeschnittene Bedeutung des asketischen Rationalismus nun auch f\u00fcr den Inhalt der <i>sozialpolitischen<\/i> Ethik, also f\u00fcr die Art der Organisation und der Funktionen der sozialen Gemeinschaften vom Konventikel bis zum Staat aufzuzeigen. Alsdann m\u00fc\u00dfte seine Beziehung zu dem humanistischen Rationalismus und dessen Lebensidealen und Kultureinfl\u00fcssen, femer zur Entwicklung des philosophischen und wissenschaftlichen Empirismus, zu der technischen Entwicklung und zu den geistigen Kulturg\u00fctern analysiert werden. Dann endlich w\u00e4re sein geschichtliches Werden von den mittelalterlichen Ans\u00e4tzen einer innerweltlichen Askese an und seine Aufl\u00f6sung in den reinen Utilitarismus <i>historisch<\/i> und durch die einzelnen Verbreitungsgebiete der asketischen Religiosit\u00e4t hindurch zu verfolgen. Daraus erst k\u00f6nnte sich das <i>Ma\u00df<\/i> der Kulturbedeutung des asketischen Protestantismus im Verh\u00e4ltnis zu anderen plastischen Elementen der modernen Kultur ergeben. <br \/>\n<cite><i>Max Weber: Die protestantische Ethik und der Geist des Kapitalismus, in: Die protestantische Ethik I, G\u00fctersloh <sup>6<\/sup>1981, S. 188 f..<\/i><\/cite><\/cite><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Weber%20im%20Zusammenhang%20%281919%2F20%29 https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Weber%20im%20Zusammenhang%20%281919%2F20%29 https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Weber%20im%20Zusammenhang%20%281919%2F20%29%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Der Haltungsturner fragt nach dem Zusammenhang eines in der Kritischen Masse notierten Zitats: Ich mag das nicht im Kommentar beantworten, sondern unter einem eigenen Punkt. Bei dem Text handelt es sich um den Schlussabschnitt aus der Aufsatzsammlung &#8222;Die protestantische Ethik&#8220; und hier genauer der erste Aufsatz &#8222;Die protestantische Ethik und der Geist des Kapitalismus&#8220;. Max [&hellip;]<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Weber%20im%20Zusammenhang%20%281919%2F20%29 https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Weber%20im%20Zusammenhang%20%281919%2F20%29 https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Weber%20im%20Zusammenhang%20%281919%2F20%29%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fweber-im-zusammenhang-191920%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"","_metis_text_length":17411,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[],"tags":[],"class_list":["post-854","post","type-post","status-publish","format-standard","hentry","entry"],"desktop_mode_lock":null,"desktop_mode_contributors":[{"userId":1,"userName":"der huflaikhan","userAvatarUrl":"https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&d=blank&r=g"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weber im Zusammenhang (1919\/20) - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weber im Zusammenhang (1919\/20) - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Der Haltungsturner fragt nach dem Zusammenhang eines in der Kritischen Masse notierten Zitats: Ich mag das nicht im Kommentar beantworten, sondern unter einem eigenen Punkt. Bei dem Text handelt es sich um den Schlussabschnitt aus der Aufsatzsammlung &#8222;Die protestantische Ethik&#8220; und hier genauer der erste Aufsatz &#8222;Die protestantische Ethik und der Geist des Kapitalismus&#8220;. Max [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2004-10-25T09:19:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T07:49:30+00:00\" \/>\n<meta name=\"author\" content=\"huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/\"},\"author\":{\"name\":\"huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\"},\"headline\":\"Weber im Zusammenhang (1919\\\/20)\",\"datePublished\":\"2004-10-25T09:19:07+00:00\",\"dateModified\":\"2023-12-18T07:49:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/\"},\"wordCount\":2509,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/\",\"name\":\"Weber im Zusammenhang (1919\\\/20) - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"datePublished\":\"2004-10-25T09:19:07+00:00\",\"dateModified\":\"2023-12-18T07:49:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2004\\\/10\\\/weber-im-zusammenhang-191920\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0085\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2005\\\/11\\\/content\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weber im Zusammenhang (1919\\\/20)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/68ba534ff428038503fc5320a3c8f932\",\"name\":\"huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g\",\"caption\":\"huflaikhan\"},\"description\":\"Musikwissenschaftler, Ideologiekritiker seit 1964.\",\"sameAs\":[\"https:\\\/\\\/kritische-masse.de\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/huflaikhan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weber im Zusammenhang (1919\/20) - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/","og_locale":"de_DE","og_type":"article","og_title":"Weber im Zusammenhang (1919\/20) - Kritische Masse","og_description":"Der Haltungsturner fragt nach dem Zusammenhang eines in der Kritischen Masse notierten Zitats: Ich mag das nicht im Kommentar beantworten, sondern unter einem eigenen Punkt. Bei dem Text handelt es sich um den Schlussabschnitt aus der Aufsatzsammlung &#8222;Die protestantische Ethik&#8220; und hier genauer der erste Aufsatz &#8222;Die protestantische Ethik und der Geist des Kapitalismus&#8220;. Max [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_published_time":"2004-10-25T09:19:07+00:00","article_modified_time":"2023-12-18T07:49:30+00:00","author":"huflaikhan","twitter_misc":{"Verfasst von":"huflaikhan","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/"},"author":{"name":"huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932"},"headline":"Weber im Zusammenhang (1919\/20)","datePublished":"2004-10-25T09:19:07+00:00","dateModified":"2023-12-18T07:49:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/"},"wordCount":2509,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/","name":"Weber im Zusammenhang (1919\/20) - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"datePublished":"2004-10-25T09:19:07+00:00","dateModified":"2023-12-18T07:49:30+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/weber-im-zusammenhang-191920\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"\u0085","item":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/11\/content\/"},{"@type":"ListItem","position":3,"name":"Weber im Zusammenhang (1919\/20)"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]},{"@type":"Person","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/68ba534ff428038503fc5320a3c8f932","name":"huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&d=blank&r=g","caption":"huflaikhan"},"description":"Musikwissenschaftler, Ideologiekritiker seit 1964.","sameAs":["https:\/\/kritische-masse.de"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/huflaikhan\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":[],"post_class":[["post-854","post","type-post","status-publish","format-standard","hentry","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":2177,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/04\/bloggermesse-schliesst-mit-hohen-erwartungen\/","url_meta":{"origin":854,"position":0},"title":"Bloggermesse schlie\u00dft mit hohen Erwartungen","author":"huflaikhan","date":"15. April 2007","format":false,"excerpt":"Berlin\/Spree. Die erste deutsche Bloggermesse re.pubblica [sic!] ist vorbei. Zwei Austeller, 12 H\u00e4ndler und knapp 700 Besucher verzeichnete die gr\u00f6\u00dfte deutsche Bloggermesse auf dem Messegel\u00e4nde Kalkscheune in Berlin. Die Messebetreiberorganisation zeigt sich Abschluss der Veranstaltung zufrieden und geschafft. \"Das neue Konzept ist im Wesentlichen voll aufgegangen\", meinte Pressesprecher Henning P.\u2026","rel":"","context":"Mit 8 Kommentaren","block_context":{"text":"Mit 8 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/04\/bloggermesse-schliesst-mit-hohen-erwartungen\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2932,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/12\/lebenswandel\/","url_meta":{"origin":854,"position":1},"title":"Lebenswandel","author":"huflaikhan","date":"13. Dezember 2009","format":false,"excerpt":"Verschiebung des Gewichts auf der Skala. Erst kommt die Pflicht, dann das Vergn\u00fcgen und zum Schluss die Arbeit. Meine neue protestantische Ethik sozusagen.","rel":"","context":"In \"Ich\"","block_context":{"text":"Ich","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/ich\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1648,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2006\/02\/violinkonzert\/","url_meta":{"origin":854,"position":2},"title":"Violinkonzert","author":"huflaikhan","date":"26. Februar 2006","format":false,"excerpt":"Das Urheberrecht erlischt \u2014 wie bekannt \u2014 70 Jahre nach dem Tod des Urhebers. 1935 starb der Komponist Alban Berg. Somit l\u00e4uft da das Urheberrecht an den Werken aus. Vielleicht nicht ganz, weil einige Dinge erst nachtr\u00e4glich in eine Fassung kamen, die erst ab diesem Zeitpunkt dann laufen. Das h\u00e4ngt\u2026","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2060,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2007\/07\/faehler-faeaehloer\/","url_meta":{"origin":854,"position":3},"title":"F\u00e4hler, F\u00e4\u00e4hl\u00f6r","author":"huflaikhan","date":"3. Juli 2007","format":false,"excerpt":"\u201eDas ungepr\u00fcfte \u00dcbernehmen von angeblichen Zitaten, die dann auch noch aus dem Kontext gerissen werden, ist der Einstieg in den Gossenjournalismus.\u201c Don Alphonso in der Blogbar unter der \u00dcberschrift: Dreck von unten? - Lieber nochmal Nachfragen zum Fall J\u00f6rges Ich habs jetzt noch mal gepr\u00fcft, ein Zitat ist es auch\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1355,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/08\/mein-zitat-des-tages\/","url_meta":{"origin":854,"position":4},"title":"Mein Zitat des Tages","author":"huflaikhan","date":"12. August 2005","format":false,"excerpt":"Unsre Schuldigkeit hei\u00dft Lockerheit. Im Zusammenhang bei Quiri.","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":68,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2000\/06\/das-rauhe-und-das-glatte\/","url_meta":{"origin":854,"position":5},"title":"Das Rauhe und das Glatte","author":"huflaikhan","date":"30. Juni 2000","format":false,"excerpt":"Von Roscoe Mitchell bis Till Br\u00f6nner Wie antiquiert muss in diesem Zusammenhang zum Beispiel das St\u00fcck \u201eLeola\u201d von \u201eRoscoe Mitchell And The Note Factory\u201d aus dem Jahr 1998 erscheinen. Es gibt keine pr\u00e4zisen Instrumentaleins\u00e4tze, der Intonation nach ist diese Musik einfach unsauber gespielt. Dabei handelt es sich bei den Musikern\u2026","rel":"","context":"In &quot;jazzzeitung&quot;","block_context":{"text":"jazzzeitung","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/texte\/jazzzeitung\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=854"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/854\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}