{"id":856,"date":"2004-10-26T09:10:16","date_gmt":"2004-10-26T08:10:16","guid":{"rendered":"https:\/\/www.kritische-masse.de\/wordpress\/blog\/schlechte-zeiten-schlechte-zeiten\/"},"modified":"2023-12-18T08:49:30","modified_gmt":"2023-12-18T07:49:30","slug":"schlechte-zeiten-schlechte-zeiten","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2004\/10\/schlechte-zeiten-schlechte-zeiten\/","title":{"rendered":"Schlechte Zeiten \u0096 Schlechte Zeiten"},"content":{"rendered":"<p>Manchmal ist man abends hundem\u00fcde und zugleich aufgekratzt. Fernsehen ist dann gegebenenfalls das Medikament der Wahl, wenn man nicht laufend gegen einen Wand rennen mag, um ohnm\u00e4chtig zu werden. So ein Schlaf ist dann auch das Wahre nicht.<\/p>\n<p>Da es im Fernsehen jedoch nichts Neues nicht gibt, jedes Bild schon tausend Mal gesendet wurde, bietet sich der regionale Sender an, der des Nachts seinen Teletext als Programm ablaufen l\u00e4sst. Die hochinteressanten Polizeiberichte mit Schl\u00e4gereien wegen Kleinigkeiten: Beschimpfungen, Anzeigen und Gegenanzeigen. <\/p>\n<p>Doch auch der Kleinanzeigenmarkt wird urpl\u00f6tzlich wieder zum Spiegel der Situation eines schleichenden gesellschaftlichen Umbaus.<\/p>\n<p><%image(20041026-teletext.jpg|500|428|Teletext nach Mitternacht)%><\/p>\n<p>Den Spa\u00df, dass da jemand eine Stelle sucht zum Best\u00fccken von Automaten mit S\u00fc\u00dfigkeiten und gleichzeitig zum Verkauf drei T\u00fcten mit Kinder \u00dc-Eiern (ohne Schoki) auffordert, lasse ich aus. Das ist zwar witzig, aber es ist in Wirklichkeit nat\u00fcrlich alles andere als witzig f\u00fcr den oder die, die diesen Weg einschlagen muss. Es ist wohl kaum anzunehmen, dass es sich um einen Abzocker handelt, auch wenn der- oder diejenige im Besitz einer Mobiltelefon-Telefonnummer ist. Unweigerlich f\u00e4llt mir dabei die Zeit der M\u00e4dchen und M\u00e4nner ein, in der man Schwefelh\u00f6lzchen verkaufen musste.<br \/>\n<!--break--><br \/>\nZwar ist der Kleinanzeigenteil einer Zeitung nicht &#8222;die Welt&#8220;, aber er ist f\u00fcr einen Turmsitzer zumindest der literarische Abfall auch von Gesellschaft: &#8222;konkrete Prosa, konkrete Lyrik.&#8220; Der Komponist Hanns Eisler hatte um 1927\/28 einmal ausdr\u00fccklich unter dem Titel &#8222;Zeitungsausschnitte&#8220; derartige Texte zu einem Liederzyklus vertont. Adorno bemerkte zu diesen St\u00fccken 1929.<br \/>\n<cite>Die Lieder mit den niedrigen, banalen, oft infantilen Texten sind keine Parodien; es wird nichts parodiert darin, nicht einmal die staubigen Gef\u00fchle, nicht einmal die zerschlissenen Worte, die vorkommen. Der Angriff, den sie unternehmen, gilt dem Recht lyrischer Bekundung als solcher und nimmt seine Gewalt aus der Politik, nicht aus der \u00e4sthetischen Reflexion. In einer Situation &#8212; so wenigstens die Logik der Lieder &#8211;, in der die gesellschaftlichen Verh\u00e4ltnisse derart Macht haben \u00fcber den einzelnen, da\u00df seine Freiheit Schein und die \u00e4sthetische Mitteilung solcher Freiheit, die personale Lyrik, Ideologie ist, kommt der personalen Lyrik weder Wahrheit in sich noch Interesse in der Gesellschaft zu.<br \/>\n<cite>[Band 18: Musikalische Schriften V: Eisler: Zeitungsausschnitte. F\u00fcr Gesang und Klavier, op. 11. Digitale Bibliothek Band 97: Theodor W. Adorno: Gesammelte Schriften, S. 15163 (vgl. GS 18, S. 524)]<\/cite><\/cite><br \/>\nSp\u00e4ter, in den 70er\/80er Jahren ging der Wiener Dichter und Komponist Gerhard R\u00fchm an eine \u00e4hnliche Thematik heran. In der Ahnung, dass das Studium der Zeitungsprosa und -lyrik mindestens ebenso geeignet ist, etwas von der Gegenwart zur Sprache zu bringen &#8212; vor allem vermittelt an das b\u00fcrgerliche Konzertpublikum, das sich lieber mit Eichendorff, Goethe, George und H\u00f6lderlin assoziieren will.<\/p>\n<p>Kleinanzeigen sind Spuren, Spuren von pers\u00f6nlichen (gewiss nicht nur privaten) Katastrophen; Bruchst\u00fccke, die vermutlich mehr aussagen \u00fcber das Ganze als manche Enquete, die meisten Gutachten und das politische Gespr\u00e4ch auf h\u00f6chster uni- oder multilateraler Ebene. Das Elend des Gew\u00f6hnlichen. Das Elend im Gew\u00f6hnlichen. Gleichzeitig sind diese Anzeigen wider Willen und wider Intention Manifeste beziehungsweise Pamphlete des Alltags.<br \/>\n<!--more--><br \/>\nManchmal ist man abends hundem\u00fcde und zugleich aufgekratzt. Fernsehen ist dann gegebenenfalls das Medikament der Wahl, wenn man nicht laufend gegen einen Wand rennen mag, um ohnm\u00e4chtig zu werden. So ein Schlaf ist dann auch das Wahre nicht.<\/p>\n<p>Da es im Fernsehen jedoch nichts Neues nicht gibt, jedes Bild schon tausend Mal gesendet wurde, bietet sich der regionale Sender an, der des Nachts seinen Teletext als Programm ablaufen l\u00e4sst. Die hochinteressanten Polizeiberichte mit Schl\u00e4gereien wegen Kleinigkeiten: Beschimpfungen, Anzeigen und Gegenanzeigen. <\/p>\n<p>Doch auch der Kleinanzeigenmarkt wird urpl\u00f6tzlich wieder zum Spiegel der Situation eines schleichenden gesellschaftlichen Umbaus.<\/p>\n<p><%image(20041026-teletext.jpg|500|428|Teletext nach Mitternacht)%><\/p>\n<p>Den Spa\u00df, dass da jemand eine Stelle sucht zum Best\u00fccken von Automaten mit S\u00fc\u00dfigkeiten und gleichzeitig zum Verkauf drei T\u00fcten mit Kinder \u00dc-Eiern (ohne Schoki) auffordert, lasse ich aus. Das ist zwar witzig, aber es ist in Wirklichkeit nat\u00fcrlich alles andere als witzig f\u00fcr den oder die, die diesen Weg einschlagen muss. Es ist wohl kaum anzunehmen, dass es sich um einen Abzocker handelt, auch wenn der- oder diejenige im Besitz einer Mobiltelefon-Telefonnummer ist. Unweigerlich f\u00e4llt mir dabei die Zeit der M\u00e4dchen und M\u00e4nner ein, in der man Schwefelh\u00f6lzchen verkaufen musste.<br \/>\n<!--break--><br \/>\nZwar ist der Kleinanzeigenteil einer Zeitung nicht &#8222;die Welt&#8220;, aber er ist f\u00fcr einen Turmsitzer zumindest der literarische Abfall auch von Gesellschaft: &#8222;konkrete Prosa, konkrete Lyrik.&#8220; Der Komponist Hanns Eisler hatte um 1927\/28 einmal ausdr\u00fccklich unter dem Titel &#8222;Zeitungsausschnitte&#8220; derartige Texte zu einem Liederzyklus vertont. Adorno bemerkte zu diesen St\u00fccken 1929.<br \/>\n<cite>Die Lieder mit den niedrigen, banalen, oft infantilen Texten sind keine Parodien; es wird nichts parodiert darin, nicht einmal die staubigen Gef\u00fchle, nicht einmal die zerschlissenen Worte, die vorkommen. Der Angriff, den sie unternehmen, gilt dem Recht lyrischer Bekundung als solcher und nimmt seine Gewalt aus der Politik, nicht aus der \u00e4sthetischen Reflexion. In einer Situation &#8212; so wenigstens die Logik der Lieder &#8211;, in der die gesellschaftlichen Verh\u00e4ltnisse derart Macht haben \u00fcber den einzelnen, da\u00df seine Freiheit Schein und die \u00e4sthetische Mitteilung solcher Freiheit, die personale Lyrik, Ideologie ist, kommt der personalen Lyrik weder Wahrheit in sich noch Interesse in der Gesellschaft zu.<br \/>\n<cite>[Band 18: Musikalische Schriften V: Eisler: Zeitungsausschnitte. F\u00fcr Gesang und Klavier, op. 11. Digitale Bibliothek Band 97: Theodor W. Adorno: Gesammelte Schriften, S. 15163 (vgl. GS 18, S. 524)]<\/cite><\/cite><br \/>\nSp\u00e4ter, in den 70er\/80er Jahren ging der Wiener Dichter und Komponist Gerhard R\u00fchm an eine \u00e4hnliche Thematik heran. In der Ahnung, dass das Studium der Zeitungsprosa und -lyrik mindestens ebenso geeignet ist, etwas von der Gegenwart zur Sprache zu bringen &#8212; vor allem vermittelt an das b\u00fcrgerliche Konzertpublikum, das sich lieber mit Eichendorff, Goethe, George und H\u00f6lderlin assoziieren will.<\/p>\n<p>Kleinanzeigen sind Spuren, Spuren von pers\u00f6nlichen (gewiss nicht nur privaten) Katastrophen; Bruchst\u00fccke, die vermutlich mehr aussagen \u00fcber das Ganze als manche Enquete, die meisten Gutachten und das politische Gespr\u00e4ch auf h\u00f6chster uni- oder multilateraler Ebene. Das Elend des Gew\u00f6hnlichen. Das Elend im Gew\u00f6hnlichen. Gleichzeitig sind diese Anzeigen wider Willen und wider Intention Manifeste beziehungsweise Pamphlete des Alltags.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-small\"><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=Schlechte%20Zeiten%20%C2%96%20Schlechte%20Zeiten https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fschlechte-zeiten-schlechte-zeiten%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#6364FF\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#6364FF\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\" style=\"color:#6364FF\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fschlechte-zeiten-schlechte-zeiten%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=Schlechte%20Zeiten%20%C2%96%20Schlechte%20Zeiten https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fschlechte-zeiten-schlechte-zeiten%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#0085ff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0085ff\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0085ff\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button threema shariff-nocustomcolor shariff-mobile\" style=\"background-color:#4fbc24\"><a href=\"threema:\/\/compose?text=Schlechte%20Zeiten%20%C2%96%20Schlechte%20Zeiten%20https%3A%2F%2Fwww.kritische-masse.de%2Flogbuch%2F2004%2F10%2Fschlechte-zeiten-schlechte-zeiten%2F\" title=\"Bei Threema teilen\" aria-label=\"Bei Threema teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#1f1f1f; color:#1f1f1f\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#1f1f1f\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#1f1f1f\" d=\"M30.8 10.9c-0.3-1.4-0.9-2.6-1.8-3.8-2-2.6-5.5-4.5-9.4-5.2-1.3-0.2-1.9-0.3-3.5-0.3s-2.2 0-3.5 0.3c-4 0.7-7.4 2.6-9.4 5.2-0.9 1.2-1.5 2.4-1.8 3.8-0.1 0.5-0.2 1.2-0.2 1.6 0 0.4 0.1 1.1 0.2 1.6 0.4 1.9 1.3 3.4 2.9 5 0.8 0.8 0.8 0.8 0.7 1.3 0 0.6-0.5 1.6-1.7 3.6-0.3 0.5-0.5 0.9-0.5 0.9 0 0.1 0.1 0.1 0.5 0 0.8-0.2 2.3-0.6 5.6-1.6 1.1-0.3 1.3-0.4 2.3-0.4 0.8 0 1.1 0 2.3 0.2 1.5 0.2 3.5 0.2 4.9 0 5.1-0.6 9.3-2.9 11.4-6.3 0.5-0.9 0.9-1.8 1.1-2.8 0.1-0.5 0.2-1.1 0.2-1.6 0-0.7-0.1-1.1-0.2-1.6-0.3-1.4 0.1 0.5 0 0zM20.6 17.3c0 0.4-0.4 0.8-0.8 0.8h-7.7c-0.4 0-0.8-0.4-0.8-0.8v-4.6c0-0.4 0.4-0.8 0.8-0.8h0.2l0-1.6c0-0.9 0-1.8 0.1-2 0.1-0.6 0.6-1.2 1.1-1.7s1.1-0.7 1.9-0.8c1.8-0.3 3.7 0.7 4.2 2.2 0.1 0.3 0.1 0.7 0.1 2.1v0 1.7h0.1c0.4 0 0.8 0.4 0.8 0.8v4.6zM15.6 7.3c-0.5 0.1-0.8 0.3-1.2 0.6s-0.6 0.8-0.7 1.3c0 0.2 0 0.8 0 1.5l0 1.2h4.6v-1.3c0-1 0-1.4-0.1-1.6-0.3-1.1-1.5-1.9-2.6-1.7zM25.8 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM18.1 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2zM10.4 28.2c0 1.2-1 2.2-2.1 2.2s-2.1-1-2.1-2.1c0-1.2 1-2.1 2.2-2.1s2.2 1 2.2 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#1f1f1f\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button rss shariff-nocustomcolor\" style=\"background-color:#ff8c00\"><a href=\"https:\/\/www.kritische-masse.de\/logbuch\/feed\/rss\/\" title=\"RSS-feed\" aria-label=\"RSS-feed\" role=\"button\" class=\"shariff-link\" style=\"; background-color:#fe9312; color:#fe9312\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#fe9312\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fe9312\" d=\"M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#fe9312\">RSS-feed<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#a8a8a8\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#999; color:#999\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#999\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Manchmal ist man abends hundem\u00fcde und zugleich aufgekratzt. Fernsehen ist dann gegebenenfalls das Medikament der Wahl, wenn man nicht laufend gegen einen Wand rennen mag, um ohnm\u00e4chtig zu werden. So ein Schlaf ist dann auch das Wahre nicht. Da es im Fernsehen jedoch nichts Neues nicht gibt, jedes Bild schon tausend Mal gesendet wurde, bietet [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_metis_text_type":"","_metis_text_length":6851,"_post_count":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[],"tags":[],"class_list":["post-856","post","type-post","status-publish","format-standard","hentry","entry"],"desktop_mode_lock":null,"desktop_mode_contributors":[],"desktop_mode_attached_media":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","categories_names":[],"post_class":[["post-856","post","type-post","status-publish","format-standard","hentry","entry"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/501e6823cd63847c2e8d3e53092cfbaf5f572cd136981466e10cf90502235bec?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":2624,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2009\/10\/wirres-fernsehen\/","url_meta":{"origin":856,"position":0},"title":"Wirres Fernsehen","author":"huflaikhan","date":"26. Oktober 2009","format":false,"excerpt":"Verstolpert soll Schwarz-Gelb haben den Auftakt. Das Gegenteil ist richtig. Sie haben die erste SPD-Regierung seit 35 Jahren ins Amt gehoben. Das kann man nat\u00fcrlich verstolpern nennen. Aber Trittin noch besser. Man habe Wahlversprechen gebrochen. Zum Beispiel, dass man sagte, alles bleibt schlecht und schwere Zeiten stehen bevor, man werde\u2026","rel":"","context":"In &quot;die Urteilskraft&quot;","block_context":{"text":"die Urteilskraft","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/dieurteilskraft\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":100,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2008\/12\/aufmerksamkeitsenthaltsamkeits-atrophie\/","url_meta":{"origin":856,"position":1},"title":"Aufmerksamkeitsenthaltsamkeits-Atrophie","author":"huflaikhan","date":"27. Dezember 2008","format":false,"excerpt":"Dabei wird seit einigen Jahren schon hartn\u00e4ckig am K\u00f6rper des \u00f6ffentlich-rechtlichen Rundfunks gek\u00e4mpft. Die Initiative \u201eDas GANZE Werk\u201c k\u00e4mpft sich Sendestrecke f\u00fcr Sendestrecke, Jingle f\u00fcr Jingle, durch den aktuellen Rundfunkwahnsinn und macht trotzig manchen Boden gut \u2013 gegen die zunehmende Selbstdisqualifizierung des Rundfunks im Norden und in Berlin. Statt spektakul\u00e4rer\u2026","rel":"","context":"In &quot;den Rundfunk&quot;","block_context":{"text":"den Rundfunk","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/denrundfunk\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8604,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2015\/12\/urheberrecht\/","url_meta":{"origin":856,"position":2},"title":"Die Wunder des Urheberrechts","author":"der huflaikhan","date":"21. Dezember 2015","format":false,"excerpt":"Es ist egal, was hinten rauskommt, so muss man wohl ein Urteil des Bundesgerichtshofs (BGH) interpretieren, das j\u00fcngst ergangen ist. Danach wollte die GEMA von einem Hotelbetreiber, der Fernseher in seinen R\u00e4umen stehen hat, die terrestrisch gesendete Signale aufnehmen, auf Zahlung einer gewissen Summe in Anspruch nehmen. In den Vorverfahren\u2026","rel":"","context":"In &quot;das Urheberrecht&quot;","block_context":{"text":"das Urheberrecht","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/das-urheberrecht\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1068,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/02\/gewinnverbot\/","url_meta":{"origin":856,"position":3},"title":"Gewinnverbot","author":"huflaikhan","date":"18. Februar 2005","format":false,"excerpt":"Unter dem Leitbegriff \u201eGewinnen geh\u00f6rt nicht zum t\u00e4glichen Brot\u201c (Urteil vom 21.12.2004, Az.: 33 O 15954\/04) hat das Landgericht einem Fernsehsender (ich erinnere) seinen Mitspielausschluss Recht gegeben. Um folgendes ging es: Gewinne von mehr als 20.000,- \u0080 klagte ein eifriger Zuschauer ein, die er innerhalb eines halben Jahres in Fernsehgewinnspielen\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":94,"url":"https:\/\/www.kritische-masse.de\/logbuch\/1999\/10\/der-innere-browning-oder-mit-musik-im-bilde\/","url_meta":{"origin":856,"position":4},"title":"Der innere Browning oder: Mit Musik im Bilde","author":"huflaikhan","date":"1. Oktober 1999","format":false,"excerpt":"\u201eWie kommt es, dass immer mehr Deutsche Marshall G\u00f6ring zustimmen, der sich seinerzeit br\u00fcstete, \u201aWenn ich das Wort Kultur h\u00f6re, ziehe ich meinen Browning\u2018? Was ist geschehen, dass \u2013 wir reden von den Massenmedien \u2013 die Massen fl\u00fcchten, wenn Kultur angesagt ist? Hat sich die Gesellschaft ge\u00e4ndert \u2013 oder gar\u2026","rel":"","context":"In &quot;Buch&quot;","block_context":{"text":"Buch","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/texte\/rezension\/buch\/"},"img":{"alt_text":"Buchtitel Suhrkamp (Montage: Hufner)","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/1999\/10\/nmz9910Medi.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1083,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/02\/die-zeit-dossier-rettet-das-radio\/","url_meta":{"origin":856,"position":5},"title":"Die Zeit &#8211; Dossier : Rettet das Radio!","author":"huflaikhan","date":"25. Februar 2005","format":false,"excerpt":"Na endlich, eine Hamburger Wochenzeitung nimmt sich des aktuellen Problems des NDR \u201eKultur\u201c an. Anruf beim Norddeutschen Rundfunk, Bitte um einen Termin mit dem Programmdirektor Gernot Romann. Doch, gro\u00dfe \u00dcberraschung, Herr Romann hat keine Zeit, heute nicht, morgen nicht, die n\u00e4chsten Wochen nicht. Die Pressestelle bittet, die Fragen schriftlich einzureichen.\u2026","rel":"","context":"Mit 2 Kommentaren","block_context":{"text":"Mit 2 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/02\/die-zeit-dossier-rettet-das-radio\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=856"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/856\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}