{"id":8819,"date":"2020-02-12T17:15:01","date_gmt":"2020-02-12T16:15:01","guid":{"rendered":"https:\/\/musikunrat.de\/?p=1996"},"modified":"2020-02-12T17:15:01","modified_gmt":"2020-02-12T16:15:01","slug":"vertrauen-und-validitaet","status":"publish","type":"post","link":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/","title":{"rendered":"Vertrauen und Validit\u00e4t"},"content":{"rendered":"<p>Wenn der Staat die Systeme infiltriert und zwar auf eine Weise, die von neutraler Seite nicht nachvollziehbar ist, indem er zum Beispiel Spitzel in Organisationen einschleust, indem er zum Beispiel Trojaner auf fremden Computern platziert, indem er den Kommunikationsverkehr belauscht; so ein Staat kann da nicht (mehr) rechtsstaatlich agieren. Er hat die Staatssicherheit in die technischen Systeme gelegt, warum sollte er sie nicht auch in die zwischenmenschlichen Beziehungen ausweiten.<\/p>\n<p>Man k\u00f6nnte es vielleicht zur\u00fcckdrehen: Nicht das Internet ist kaputt, sondern es sind diejenigen, die es durchherrschen.*<\/p>\n<p>Wenn aber die Informationen aus den Netzen nicht mehr als valide angesehen werden k\u00f6nnen, weil sie jederzeit manipulierbar sind, verschwindet der Kitt, der die Menschen zusammenhalten kann. Dann ist das Ger\u00fccht, der Verdacht gr\u00f6\u00dfer und ein schwerer Schatten \u00fcber allen breitet sich aus, K\u00e4lte verstr\u00f6mend.<\/p>\n<p>Ich erinnere mich immer wieder an Alexander Kluges S\u00e4tze zum Thema Vertrauen in seiner Schrift \u201eDie Kunst, Unterschiede zu machen\u201c:<\/p>\n<blockquote><p>Der Mensch neigt dazu, Vertrauen zu produzieren. Das ist eine Mitgift, eine F\u00e4higkeit. Lieber irren wir uns, als nicht zu vertrauen. Das ist als Gravitationskraft unter Menschen me\u00dfbar. Wo ein Vertrauen sich ausdehnt, k\u00f6nnen Menschen zaubern.<\/p><\/blockquote>\n<p>Man muss gegen seine Neigung angehen, sich selbst verstellen, sich vor sich selbst verstellen und in Schutz nehmen. Oder den Irrtum in Kauf nehmen.<\/p>\n<hr \/>\n<p><strong>Update 2020: <\/strong><\/p>\n<p><strong>* Es ist in Teilen aber auch anders:<\/strong> das Misstrauen wird zur Energiequelle der Desinformation selbst. Und selbst diesseits (rechts)staatlichen Handelns. Der Rechtsstaat, der auf solche Menschen zur\u00fcckgreifen kann, muss selbst gar nicht mehr aktiv werden, sondern kann zusehen, wie er unrechtsstaatlich von innen heraus wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn der Staat die Systeme infiltriert und zwar auf eine Weise, die von neutraler Seite nicht nachvollziehbar ist, indem er zum Beispiel Spitzel in Organisationen einschleust, indem er zum Beispiel Trojaner auf fremden Computern platziert, indem er den Kommunikationsverkehr belauscht; so ein Staat kann da nicht (mehr) rechtsstaatlich agieren. Er hat die Staatssicherheit in die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","_metis_text_type":"standard","_metis_text_length":1778,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"activitypub_content_warning":"","activitypub_content_visibility":"","activitypub_max_image_attachments":4,"activitypub_interaction_policy_quote":"anyone","activitypub_status":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":"","jetpack_publicize_message":"Vertrauen und Validit\u00e4t (2014) - Der Unrechtsstaat von innen heraus (2020).","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2648],"tags":[2315,4004,3148,4005,2918],"class_list":["post-8819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dieurteilskraft","tag-internet","tag-misstrauen","tag-technik","tag-verdacht","tag-vertrauen","entry","has-media"],"desktop_mode_lock":null,"desktop_mode_contributors":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vertrauen und Validit\u00e4t - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vertrauen und Validit\u00e4t - Kritische Masse\" \/>\n<meta property=\"og:description\" content=\"Wenn der Staat die Systeme infiltriert und zwar auf eine Weise, die von neutraler Seite nicht nachvollziehbar ist, indem er zum Beispiel Spitzel in Organisationen einschleust, indem er zum Beispiel Trojaner auf fremden Computern platziert, indem er den Kommunikationsverkehr belauscht; so ein Staat kann da nicht (mehr) rechtsstaatlich agieren. Er hat die Staatssicherheit in die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/hufner\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-12T16:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"der huflaikhan\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"der huflaikhan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/\"},\"author\":{\"name\":\"der huflaikhan\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"headline\":\"Vertrauen und Validit\u00e4t\",\"datePublished\":\"2020-02-12T16:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/\"},\"wordCount\":274,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2007\\\/01\\\/labelle1.jpg?fit=1024%2C683&ssl=1\",\"keywords\":[\"Internet\",\"Misstrauen\",\"Technik\",\"Verdacht\",\"Vertrauen\"],\"articleSection\":[\"die Urteilskraft\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/\",\"name\":\"Vertrauen und Validit\u00e4t - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2007\\\/01\\\/labelle1.jpg?fit=1024%2C683&ssl=1\",\"datePublished\":\"2020-02-12T16:15:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2007\\\/01\\\/labelle1.jpg?fit=1024%2C683&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2007\\\/01\\\/labelle1.jpg?fit=1024%2C683&ssl=1\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/2020\\\/02\\\/vertrauen-und-validitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vertrauen und Validit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"],\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/author\\\/martin_d1juqiu5\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vertrauen und Validit\u00e4t - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/","og_locale":"de_DE","og_type":"article","og_title":"Vertrauen und Validit\u00e4t - Kritische Masse","og_description":"Wenn der Staat die Systeme infiltriert und zwar auf eine Weise, die von neutraler Seite nicht nachvollziehbar ist, indem er zum Beispiel Spitzel in Organisationen einschleust, indem er zum Beispiel Trojaner auf fremden Computern platziert, indem er den Kommunikationsverkehr belauscht; so ein Staat kann da nicht (mehr) rechtsstaatlich agieren. Er hat die Staatssicherheit in die [&hellip;]","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/","og_site_name":"Kritische Masse","article_publisher":"https:\/\/www.facebook.com\/hufner","article_author":"https:\/\/www.facebook.com\/hufner","article_published_time":"2020-02-12T16:15:01+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg","type":"image\/jpeg"}],"author":"der huflaikhan","twitter_misc":{"Verfasst von":"der huflaikhan","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#article","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/"},"author":{"name":"der huflaikhan","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"headline":"Vertrauen und Validit\u00e4t","datePublished":"2020-02-12T16:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/"},"wordCount":274,"commentCount":0,"publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg?fit=1024%2C683&ssl=1","keywords":["Internet","Misstrauen","Technik","Verdacht","Vertrauen"],"articleSection":["die Urteilskraft"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/","name":"Vertrauen und Validit\u00e4t - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#primaryimage"},"image":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg?fit=1024%2C683&ssl=1","datePublished":"2020-02-12T16:15:01+00:00","breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#primaryimage","url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg?fit=1024%2C683&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg?fit=1024%2C683&ssl=1","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/2020\/02\/vertrauen-und-validitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"Vertrauen und Validit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"],"url":"https:\/\/www.kritische-masse.de\/logbuch\/author\/martin_d1juqiu5\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2007\/01\/labelle1.jpg?fit=1024%2C683&ssl=1","categories_names":["die Urteilskraft"],"post_class":[["post-8819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dieurteilskraft","tag-internet","tag-misstrauen","tag-technik","tag-verdacht","tag-vertrauen","entry","has-media"]],"author_avatar":["<img alt='' src='https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=96&#038;d=blank&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/c23aee426d58e69f14ef471114d4cac215eec702ee1bc331e2a62ea77e96ed60?s=192&#038;d=blank&#038;r=g 2x' class='avatar avatar-96 photo' height='96' width='96' loading='lazy' decoding='async'\/>"],"featured_video":null,"jetpack-related-posts":[{"id":3322,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2014\/02\/vertrauen-und-validit-t\/","url_meta":{"origin":8819,"position":0},"title":"Vertrauen und Validit\u00e4t","author":"huflaikhan","date":"12. Februar 2014","format":false,"excerpt":"Wenn der Staat die Systeme infiltriert und zwar auf eine Weise, die von neutraler Seite nicht nachvollziehbar ist, indem er zum Beispiel Spitzel in Organisationen einschleust, indem er zum Beispiel Trojaner auf fremden Computern platziert, indem er den Kommunikationsverkehr belauscht; so ein Staat kann nicht mehr rechtsstaatlich agieren. Er hat\u2026","rel":"","context":"In &quot;Angriff auf \u2026&quot;","block_context":{"text":"Angriff auf \u2026","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/"},"img":{"alt_text":"Schwer zu durchschauen. Foto: Hufner","src":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/02\/winnerjazz-1030121.jpg?fit=1067%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/02\/winnerjazz-1030121.jpg?fit=1067%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/02\/winnerjazz-1030121.jpg?fit=1067%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/02\/winnerjazz-1030121.jpg?fit=1067%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2014\/02\/winnerjazz-1030121.jpg?fit=1067%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3005,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2011\/09\/die-zukunft-der-netze-1979-und-das-ende-der-ffentlichkeit-2011\/","url_meta":{"origin":8819,"position":1},"title":"Die Zukunft der Netze (1979) und das Ende der \u00d6ffentlichkeit (2011)","author":"huflaikhan","date":"8. September 2011","format":false,"excerpt":"Kreidler hat mich daran erinnert, dass auch ich einmal vor einiger Zeit im Auge des philosophischen Hurrikans der Postmoderne mich befand. Wir lasen damals ein Buch mit dem Titel \"Postmoderne oder Der Kampf um die Zukunft\". Es erschien 1988, herausgegeben von Peter Kemper. es war Begleittext zu einer Senderreihe des\u2026","rel":"","context":"In \"Internet\"","block_context":{"text":"Internet","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/internet\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1505,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/11\/geht-doch\/","url_meta":{"origin":8819,"position":2},"title":"Geht doch","author":"huflaikhan","date":"11. November 2005","format":false,"excerpt":"Dei Vernunft hat gesiegt, die Parteien sind sich einig. Super: Vorw\u00e4rts Deutschland. Und Roland Koch, dem Semmel heute einen wunderbaren Eintrag gewidmet hat, hat sich wieder einmal als Menschenkenner geoutet. Sein Menschenbild geht wie folgt. \u201eKnast f\u00fcr Rentner!\u201c So in etwa erkl\u00e4rte die kommende Mehrwertsteuererh\u00f6hung. Denn, so eben im Mittagsmagazin,\u2026","rel":"","context":"\u00c4hnlicher Beitrag","block_context":{"text":"\u00c4hnlicher Beitrag","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8371,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2011\/11\/vertrauen-und-politik-luhmann\/","url_meta":{"origin":8819,"position":3},"title":"Vertrauen und Politik [Luhmann]","author":"der huflaikhan","date":"8. November 2011","format":false,"excerpt":"Liegt schon lange bei mir herum. Vor allem die nachfolgende Passage harrt der Deutung. Luhmann schreibt 1968 (!, erste Auflage): Die Metapher vom 'Staatsvertrag', durch den freie Naturmenschen sich selbst oder dem eingesetzten Souver\u00e4n Vertrauen gew\u00e4hren, entspricht keine Wirklichkeit. Gewi\u00df: der Staatsb\u00fcrger w\u00e4hlt. Aber die politische Wahl ist keine Beauftragung\u2026","rel":"","context":"In &quot;die Politik&quot;","block_context":{"text":"die Politik","link":"https:\/\/www.kritische-masse.de\/logbuch\/category\/angriffauf\/die-politik\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1293,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/06\/nochmal-zum-thema-populismus-mannomann\/","url_meta":{"origin":8819,"position":4},"title":"Nochmal zum Thema Populismus, mannomann","author":"huflaikhan","date":"22. Juni 2005","format":false,"excerpt":"Das Sehpferdchen nimmt im Wahlblog die Bild-Thesen von Oskar Lafontaine unter die Lupe. Reden wir nicht von der Bild-Zeitung und Oskars Kolumne darin. Da hat so mancher, nicht sogar mal Wolf Biermann, geschrieben, wars nicht so. Obwohl: Geschrieben? Sagen wir besser getextet. Also wir lesen: 7. Spitzensteuersatz anheben Sehr popul\u00e4re\u2026","rel":"","context":"Mit 6 Kommentaren","block_context":{"text":"Mit 6 Kommentaren","link":"https:\/\/www.kritische-masse.de\/logbuch\/2005\/06\/nochmal-zum-thema-populismus-mannomann\/#comments"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3009,"url":"https:\/\/www.kritische-masse.de\/logbuch\/2011\/11\/vertrauen-und-politik\/","url_meta":{"origin":8819,"position":5},"title":"Vertrauen und Politik","author":"huflaikhan","date":"8. November 2011","format":false,"excerpt":"Liegt schon lange bei mir herum. Vor allem die nachfolgende Passage harrt der Deutung.Luhmann schreibt 1968 (!, erste Auflage):Die Metapher vom 'Staatsvertrag', durch den freie Naturmenschen sich selbst oder dem eingesetzten Souver\u00e4n Vertrauen gew\u00e4hren, entspricht keine Wirklichkeit. Gewi\u00df: der Staatsb\u00fcrger w\u00e4hlt. Aber die politische Wahl ist keine Beauftragung mit Interessenvertretung.\u2026","rel":"","context":"In \"Luhmann\"","block_context":{"text":"Luhmann","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/luhmann\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/8819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/comments?post=8819"}],"version-history":[{"count":0,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts\/8819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media\/1997"}],"wp:attachment":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/media?parent=8819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/categories?post=8819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags?post=8819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}