{"id":2572,"count":2,"description":"","link":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/","name":"Max Weber","slug":"maxweber","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Max Weber Archive - Kritische Masse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Max Weber Archive - Kritische Masse\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/\" \/>\n<meta property=\"og:site_name\" content=\"Kritische Masse\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/tag\\\/maxweber\\\/\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/tag\\\/maxweber\\\/\",\"name\":\"Max Weber Archive - Kritische Masse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/tag\\\/maxweber\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/tag\\\/maxweber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Max Weber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#website\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"name\":\"kritische masse\",\"description\":\"amt f\u00fcr vermassungsschutz\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\"},\"alternateName\":\"das logbuch der kritischen masse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/#\\\/schema\\\/person\\\/14c491f46504e7f6b79db161f76def1c\",\"name\":\"der huflaikhan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"url\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\",\"width\":512,\"height\":512,\"caption\":\"der huflaikhan\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-kritischmasse_man_512.jpg\"},\"description\":\"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.\",\"sameAs\":[\"https:\\\/\\\/www.kritische-masse.de\\\/logbuch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/hufner\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Max Weber Archive - Kritische Masse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/","og_locale":"de_DE","og_type":"article","og_title":"Max Weber Archive - Kritische Masse","og_url":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/","og_site_name":"Kritische Masse","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/","url":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/","name":"Max Weber Archive - Kritische Masse","isPartOf":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website"},"breadcrumb":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kritische-masse.de\/logbuch\/tag\/maxweber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kritische-masse.de\/logbuch\/"},{"@type":"ListItem","position":2,"name":"Max Weber"}]},{"@type":"WebSite","@id":"https:\/\/www.kritische-masse.de\/logbuch\/#website","url":"https:\/\/www.kritische-masse.de\/logbuch\/","name":"kritische masse","description":"amt f\u00fcr vermassungsschutz","publisher":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c"},"alternateName":"das logbuch der kritischen masse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kritische-masse.de\/logbuch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.kritische-masse.de\/logbuch\/#\/schema\/person\/14c491f46504e7f6b79db161f76def1c","name":"der huflaikhan","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","url":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","contentUrl":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg","width":512,"height":512,"caption":"der huflaikhan"},"logo":{"@id":"https:\/\/www.kritische-masse.de\/logbuch\/wp-content\/uploads\/2024\/01\/cropped-kritischmasse_man_512.jpg"},"description":"Betreiber der Kritischen Masse seit 1995. Seit 2023 Wiederaufnahme. Promotion mit einer Arbeit \u00fcber Adornos kompositorische und theoretische Auseinandersetzung mit der Zw\u00f6lftontechnik. Arbeit f\u00fcr den Bayerischen und den Mitteldeutschen Rundfunk als freier Autor und Regisseur \u2013 zumindest bis Ende 2015. Online-Redaktion f\u00fcr neue musikzeitung, Jazzzeitung und Oper &amp; Tanz. Ungl\u00fccklich, aber fast taub.","sameAs":["https:\/\/www.kritische-masse.de\/logbuch\/","https:\/\/www.facebook.com\/hufner"]}]}},"_links":{"self":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags\/2572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/posts?tags=2572"},{"href":"https:\/\/www.kritische-masse.de\/logbuch\/wp-json\/wp\/v2\/episodes?tags=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}